{"id":10357,"date":"2025-05-15T12:15:24","date_gmt":"2025-05-15T10:15:24","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=10357"},"modified":"2025-05-21T14:43:33","modified_gmt":"2025-05-21T12:43:33","slug":"burberry-va-laisser-1-700-emplois-sur-le-carreau","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/","title":{"rendered":"Burberry va laisser 1.700 emplois sur le carreau"},"content":{"rendered":"<div><strong>Plomb\u00e9e par une faible\u00a0demande en Chine, la crise que traverse le secteur du luxe depuis quelques ann\u00e9es, et encore renforc\u00e9e par les droits de douane du pr\u00e9sident am\u00e9ricain Donald Trump, n&rsquo;\u00e9pargne personne. Pas m\u00eame <a href=\"https:\/\/fr.burberry.com\/?srsltid=AfmBOookQ_ZFZBLozNEwsBRys72xSA2cpTlbWFn6Sa2juA5_S7XkgqjK\">Burberry<\/a> et ses v\u00eatements avec les c\u00e9l\u00e8bres motifs \u00e0 carreaux, qui va devoir se s\u00e9parer de 18% de ses effectifs. Jusqu&rsquo;\u00e0 1.700 emplois sur 9.300 vont donc rester&#8230;sur le carreau, principalement au si\u00e8ge social, au Royaume-Uni, mais aussi dans les magasins.<\/strong><\/div>\n<div><\/div>\n<div>Cette annonce s&rsquo;explique par la baisse des ventes de la marque britannique, qui ont recul\u00e9 de 12%, particuli\u00e8rement en Asie (-16%), sur <a href=\"https:\/\/www.burberryplc.com\/investors\/results-reports-presentations\">l&rsquo;exercice fiscal d\u00e9cal\u00e9 2024-2025<\/a>. <strong>Burberry<\/strong> va d\u00e8s lors devoir faire des <strong>\u00e9conomies<\/strong> suppl\u00e9mentaires d&rsquo;environ 71 millions d&rsquo;euros d&rsquo;ici \u00e0 la fin 2027, apr\u00e8s un plan de r\u00e9duction des co\u00fbts de 47,5 millions d\u00e9j\u00e0 en cours. Avec les deux montants cumul\u00e9s, on fr\u00f4le les 120 millions d&rsquo;euros!<\/div>\n<div><\/div>\n<div>La client\u00e8le s&rsquo;est\u00a0d\u00e9tourn\u00e9e de l&rsquo;enseigne depuis quelques ann\u00e9es en raison de l&rsquo;<strong>inflation<\/strong> qui n&rsquo;a cess\u00e9 de cro\u00eetre depuis le Covid, et l&rsquo;entreprise a du mal \u00e0 retrouver ces clients perdus. Le <strong>contexte \u00e9conomique<\/strong> en Chine, o\u00f9 la demande en <strong>produits de luxe<\/strong> est faible pour le moment, et les <strong>droits de douane<\/strong> \u00e0 l&rsquo;importation mis en place par le pr\u00e9sident Trump rendent en outre la conjoncture plus complexe encore.<\/div>\n<div><\/div>\n<div>L&rsquo;an dernier; sous l&rsquo;\u00e9gide de son nouveau CEO <strong>Joshua Schulman<\/strong>, <strong>Burberry<\/strong> a mis en place une nouvelle strat\u00e9gie \u00ab\u00a0Burberry\u00a0Forward\u00a0\u00bb, qui pr\u00e9voyait la <strong>r\u00e9duction des co\u00fbts<\/strong> de 47,5 millions d&rsquo;euros. L&rsquo;objectif de l&rsquo;enseigne \u00e9tait aussi de se recentrer sur ses principaux produits que sont les v\u00eatements d&rsquo;ext\u00e9rieur comme les vestes ou les \u00e9charpes, qui b\u00e9n\u00e9ficient par exemple d\u00e9sormais de \u00ab\u00a0bars \u00e0 \u00e9charpes\u00a0\u00bb dans les boutiques.<\/div>\n<div><\/div>\n<div>\u00ab\u00a0Bien que nous \u00e9voluions dans un <strong>contexte macro\u00e9conomique difficile<\/strong> et que nous n&rsquo;en soyons qu&rsquo;aux premi\u00e8res \u00e9tapes de notre redressement, je suis plus optimiste que jamais sur le fait que les meilleurs jours de <strong>Burberry<\/strong> sont \u00e0 venir et que nous assurerons une croissance durable et rentable au fil du temps\u00a0\u00bb, a esp\u00e9r\u00e9 le CEO.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Plomb\u00e9e par une faible\u00a0demande en Chine, la crise que traverse le secteur du luxe depuis quelques ann\u00e9es, et encore renforc\u00e9e par les droits de douane du pr\u00e9sident am\u00e9ricain Donald Trump, n&rsquo;\u00e9pargne personne. Pas m\u00eame Burberry et ses v\u00eatements avec les c\u00e9l\u00e8bres motifs \u00e0 carreaux, qui va devoir se s\u00e9parer de 18% de ses effectifs. Jusqu&rsquo;\u00e0 [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":10358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1,18],"tags":[],"class_list":["post-10357","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualite","category-luxe"],"acf":[],"_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"Confront\u00e9e \u00e0 une baisse de ses ventes, Burberry va supprimer jusqu'\u00e0 1.700 emplois. C'est une nouvelle victime de la crise du march\u00e9 du luxe.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Burberry va laisser 1.700 emplois sur le carreau | Forbes Belgique<\/title>\n<meta name=\"description\" content=\"Confront\u00e9e \u00e0 une baisse de ses ventes, Burberry va supprimer jusqu&#039;\u00e0 1.700 emplois. C&#039;est une nouvelle victime de la crise du march\u00e9 du luxe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burberry va laisser 1.700 emplois sur le carreau | Forbes Belgique\" \/>\n<meta property=\"og:description\" content=\"Confront\u00e9e \u00e0 une baisse de ses ventes, Burberry va supprimer jusqu&#039;\u00e0 1.700 emplois. C&#039;est une nouvelle victime de la crise du march\u00e9 du luxe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T10:15:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T12:43:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juan Godbille\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juan Godbille\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/\"},\"author\":{\"name\":\"Juan Godbille\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/0d449791ef6199da3d469eca714eb773\"},\"headline\":\"Burberry va laisser 1.700 emplois sur le carreau\",\"datePublished\":\"2025-05-15T10:15:24+00:00\",\"dateModified\":\"2025-05-21T12:43:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg\",\"articleSection\":[\"Actualit\u00e9s\",\"Luxe\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/\",\"name\":\"Burberry va laisser 1.700 emplois sur le carreau | Forbes Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg\",\"datePublished\":\"2025-05-15T10:15:24+00:00\",\"dateModified\":\"2025-05-21T12:43:33+00:00\",\"description\":\"Confront\u00e9e \u00e0 une baisse de ses ventes, Burberry va supprimer jusqu'\u00e0 1.700 emplois. C'est une nouvelle victime de la crise du march\u00e9 du luxe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg\",\"width\":2560,\"height\":1340,\"caption\":\"LONDON, UK - 3 DECEMBER 2018: Shoppers walking by the facade to the Burberry fashion store in London's Covent Garden district on a wet winters day.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/burberry-va-laisser-1-700-emplois-sur-le-carreau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Burberry va laisser 1.700 emplois sur le carreau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/0d449791ef6199da3d469eca714eb773\",\"name\":\"Juan Godbille\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de6d740453251c69ae34e42cfef9688bc2a5c942d7cab09074e7064fbac13ac9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de6d740453251c69ae34e42cfef9688bc2a5c942d7cab09074e7064fbac13ac9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de6d740453251c69ae34e42cfef9688bc2a5c942d7cab09074e7064fbac13ac9?s=96&d=mm&r=g\",\"caption\":\"Juan Godbille\"},\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/juan-godbille\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Burberry va laisser 1.700 emplois sur le carreau | Forbes Belgique","description":"Confront\u00e9e \u00e0 une baisse de ses ventes, Burberry va supprimer jusqu'\u00e0 1.700 emplois. C'est une nouvelle victime de la crise du march\u00e9 du luxe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/","og_locale":"fr_FR","og_type":"article","og_title":"Burberry va laisser 1.700 emplois sur le carreau | Forbes Belgique","og_description":"Confront\u00e9e \u00e0 une baisse de ses ventes, Burberry va supprimer jusqu'\u00e0 1.700 emplois. C'est une nouvelle victime de la crise du march\u00e9 du luxe.","og_url":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2025-05-15T10:15:24+00:00","article_modified_time":"2025-05-21T12:43:33+00:00","og_image":[{"width":2560,"height":1340,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg","type":"image\/jpeg"}],"author":"Juan Godbille","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Juan Godbille","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/"},"author":{"name":"Juan Godbille","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/0d449791ef6199da3d469eca714eb773"},"headline":"Burberry va laisser 1.700 emplois sur le carreau","datePublished":"2025-05-15T10:15:24+00:00","dateModified":"2025-05-21T12:43:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/"},"wordCount":368,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg","articleSection":["Actualit\u00e9s","Luxe"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/","url":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/","name":"Burberry va laisser 1.700 emplois sur le carreau | Forbes Belgique","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg","datePublished":"2025-05-15T10:15:24+00:00","dateModified":"2025-05-21T12:43:33+00:00","description":"Confront\u00e9e \u00e0 une baisse de ses ventes, Burberry va supprimer jusqu'\u00e0 1.700 emplois. C'est une nouvelle victime de la crise du march\u00e9 du luxe.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/adobestock-298260305-editorial-use-only-scaled-e1747831392295.jpeg","width":2560,"height":1340,"caption":"LONDON, UK - 3 DECEMBER 2018: Shoppers walking by the facade to the Burberry fashion store in London's Covent Garden district on a wet winters day."},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/burberry-va-laisser-1-700-emplois-sur-le-carreau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Burberry va laisser 1.700 emplois sur le carreau"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/0d449791ef6199da3d469eca714eb773","name":"Juan Godbille","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/de6d740453251c69ae34e42cfef9688bc2a5c942d7cab09074e7064fbac13ac9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de6d740453251c69ae34e42cfef9688bc2a5c942d7cab09074e7064fbac13ac9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de6d740453251c69ae34e42cfef9688bc2a5c942d7cab09074e7064fbac13ac9?s=96&d=mm&r=g","caption":"Juan Godbille"},"url":"https:\/\/www.forbes.be\/fr\/author\/juan-godbille\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=10357"}],"version-history":[{"count":3,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10357\/revisions"}],"predecessor-version":[{"id":10363,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10357\/revisions\/10363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/10358"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=10357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=10357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=10357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}