{"id":10478,"date":"2025-05-20T09:27:42","date_gmt":"2025-05-20T07:27:42","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=10478"},"modified":"2025-05-21T14:40:32","modified_gmt":"2025-05-21T12:40:32","slug":"facons-entrepreneurs-entreprise-durable","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/","title":{"rendered":"8 fa\u00e7ons pour les entrepreneurs de rendre leur entreprise plus durable"},"content":{"rendered":"<p><strong>Pour de nombreux entrepreneurs, la durabilit\u00e9 est devenue une \u00e9vidence, voire une aspiration in\u00e9vitable. Cependant, entre les bonnes intentions et l&rsquo;impact r\u00e9el, se trouve souvent un labyrinthe de choix, de d\u00e9fis et d&rsquo;arbitrages. Que signifie r\u00e9ellement entreprendre de mani\u00e8re durable en 2025 ? Comment \u00e9viter de se contenter d&rsquo;une promesse vague ou d&rsquo;une fa\u00e7ade verte, et faire de la durabilit\u00e9 un avantage strat\u00e9gique \u2013 \u00e0 la fois \u00e9cologique, social et \u00e9conomique ?<\/strong><\/p>\n<p>Pour r\u00e9pondre \u00e0 ces questions, nous avons consult\u00e9 trois entreprises pour qui la durabilit\u00e9 n&rsquo;est pas une tendance mais le fondement de leur mod\u00e8le \u00e9conomique : <strong>Paveau<\/strong>, <strong>Crisp<\/strong> et <strong>Purasana<\/strong>. Chacune d&rsquo;elles aborde la <strong>durabilit\u00e9<\/strong> sous un angle diff\u00e9rent : technologie et transition agricole, d\u00e9veloppement de produits circulaires, ou encore sant\u00e9 scientifique r\u00e9glement\u00e9e. Pourtant, il existe des points communs remarquables dans leur approche : elles investissent dans la transparence, construisent des relations durables avec les fournisseurs, et osent penser de mani\u00e8re ambitieuse, sans perdre de vue la r\u00e9alit\u00e9.<\/p>\n<h2>La durabilit\u00e9 au c\u0153ur de l&rsquo;entreprise<\/h2>\n<p><strong>Paveau<\/strong> est une marque belge ax\u00e9e sur le design, d\u00e9veloppant des bouteilles d&rsquo;eau en verre r\u00e9utilisables pour encourager la consommation d&rsquo;eau du robinet et r\u00e9duire les d\u00e9chets plastiques. Ici, la <strong>durabilit\u00e9<\/strong> n&rsquo;est pas un projet isol\u00e9, mais la raison d&rsquo;\u00eatre. <a href=\"https:\/\/www.forbes.be\/nl\/groei-gentse-glaswerkmerk-paveau-bevestigt-vraag-duurzame-producten\/\" target=\"_blank\" rel=\"noopener\">Et cela rapporte \u00e9galement les chiffres verts n\u00e9cessaires, comme nous l&rsquo;avons d\u00e9j\u00e0 soulign\u00e9.<\/a> La fondatrice <strong>Isabelle De Pauw<\/strong> ne souhaite pas seulement offrir aux consommateurs un produit r\u00e9utilisable attrayant, mais encourage un changement de comportement. \u00ab Nous promouvons l&rsquo;eau du robinet au lieu des bouteilles d&rsquo;eau emball\u00e9es. C&rsquo;est une petite habitude avec un grand impact. \u00bb Sa plus grande le\u00e7on ? Commencez par une mission claire et appliquez-la dans tous les aspects de votre entreprise. \u00ab C&rsquo;est la seule fa\u00e7on d&rsquo;\u00eatre cr\u00e9dible \u00bb<\/p>\n<p><strong>Crisp<\/strong> est un supermarch\u00e9 num\u00e9rique qui propose des aliments frais, produits localement, via une cha\u00eene courte et s&rsquo;engage fortement en faveur de la <strong>durabilit\u00e9<\/strong> et de l&rsquo;agriculture r\u00e9g\u00e9n\u00e9ratrice. Ils sont le premier supermarch\u00e9 en Flandre \u00e0 obtenir la <a href=\"https:\/\/www.bcorporation.net\/en-us\/certification\/\" target=\"_blank\" rel=\"noopener\">certification B Corp<\/a> (avec un score B Impact Assessment de 109 points !) et transforment la <strong>durabilit\u00e9<\/strong> en une cha\u00eene courte, une agriculture r\u00e9g\u00e9n\u00e9rative et une utilisation intelligente de la technologie pour r\u00e9duire le gaspillage. Le CEO <strong>Tom Peeters<\/strong> d\u00e9clare : \u00ab\u00a0La <strong>durabilit\u00e9<\/strong> n&rsquo;est pas un d\u00e9partement distinct. Elle est int\u00e9gr\u00e9e dans tout notre mod\u00e8le.\u00a0\u00bb<\/p>\n<p><strong>Purasana<\/strong> est une marque belge qui d\u00e9veloppe des produits de sant\u00e9 naturels et biologiques, ax\u00e9s sur la transparence, l&rsquo;approbation scientifique et les emballages durables. Ils construisent en interne une culture de <strong>conscience environnementale<\/strong> et de cr\u00e9dibilit\u00e9 externe. \u00ab Nous basons nos revendications sur la sant\u00e9 sur les lois de l&rsquo;EFSA et les \u00e9tayons par la science, \u00bb d\u00e9clare la coordinatrice de la <strong>durabilit\u00e9 Melissa De Lombaerde<\/strong>. \u00ab cette pr\u00e9cision est non seulement n\u00e9cessaire pour la conformit\u00e9, mais aussi pour b\u00e2tir la confiance avec les clients et les partenaires. \u00bb<\/p>\n<p>Le fil rouge ? Entreprendre de <strong>mani\u00e8re durable<\/strong> est sans fin. Mais cela offre des avantages tangibles : fid\u00e9lisation des clients, des marques plus fortes, jusqu&rsquo;\u00e0 des processus plus efficaces et des relations significatives avec les partenaires. Ci-dessous, ces trois entreprises partagent leur approche, leurs le\u00e7ons et surtout : des conseils concrets pour les <strong>entrepreneurs<\/strong> qui souhaitent rendre leur entreprise plus durable, du d\u00e9veloppement de produits \u00e0 l&#8217;emballage, et de la gestion de la cha\u00eene \u00e0 la culture interne.<\/p>\n<h2>1. Faites de la durabilit\u00e9 votre fondement, pas une couche de marketing<\/h2>\n<p><strong>Entreprendre<\/strong> de <strong>mani\u00e8re durable<\/strong> commence par une conviction. \u00ab La durabilit\u00e9 ne doit pas \u00eatre un outil marketing, mais une valeur fondamentale, \u00bb d\u00e9clare <strong>Isabelle De Pauw<\/strong>, de<strong> Paveau<\/strong>. Pour elle, cela signifie : commencer par une mission claire &#8211; dans son cas : r\u00e9duire les d\u00e9chets plastiques &#8211; et la traduire dans chaque aspect de votre entreprise. Les bouteilles d&rsquo;eau r\u00e9utilisables de<strong> Paveau<\/strong> ne sont pas seulement un joli produit, mais aussi un vecteur de ce message. \u00ab Appliquez votre mission aux processus internes, au d\u00e9veloppement de produits et \u00e0 la communication. \u00bb <strong>Melissa De Lombaerde<\/strong>, de <strong>Purasana<\/strong> ajoute : \u00ab\u00a0Les entreprises doivent \u00e9viter de faire des promesses vagues. La directive de l&rsquo;UE sur les all\u00e9gations \u00e9cologiques nous oblige \u00e0 avoir une communication \u00e9tay\u00e9e et transparente. Cela vous contraint \u00e0 r\u00e9ellement ancrer la durabilit\u00e9 dans votre politique.\u00a0\u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8509 size-large\" src=\"https:\/\/www.forbes.be\/nl\/wp-content\/uploads\/2025\/04\/20240620-paveau-04-kp-004-o4a942365-1024x683.jpg\" alt=\"\" width=\"696\" height=\"464\" \/><\/p>\n<p>Isabelle De Pauw, fondatrice de Paveau<\/p>\n<h2>2. Travaillez avec des partenaires qui renforcent votre mission<\/h2>\n<p>Les partenaires externes peuvent renforcer et acc\u00e9l\u00e9rer vos objectifs durables. Chez <strong>Paveau<\/strong>, il s&rsquo;agit notamment de Plastic Bank, une organisation qui collecte le plastique et cr\u00e9e des emplois sociaux dans les r\u00e9gions vuln\u00e9rables. \u00ab Gr\u00e2ce \u00e0 nos dons, environ 20 000 bouteilles sont collect\u00e9es chaque mois. Cela a un <strong>impact<\/strong> mesurable &#8211; tant sur le plan \u00e9cologique que social, \u00bb selon Isabelle.<\/p>\n<p><strong>Crisp<\/strong> collabore avec des agriculteurs r\u00e9g\u00e9n\u00e9ratifs via le r\u00e9seau &lsquo;Boeren Natuurlijk&rsquo;. \u00ab Nous soutenons ces agriculteurs structurellement en achetant l&rsquo;ensemble de leur r\u00e9colte, m\u00eame si elle est saisonni\u00e8re et moins pr\u00e9visible, \u00bb explique <strong>Tom Peeters<\/strong>. \u00ab\u00a0Cette s\u00e9curit\u00e9 d&rsquo;achat est essentielle pour rendre ce mode de culture \u00e9volutif.\u00a0\u00bb<\/p>\n<p>Chez <strong>Purasana<\/strong>, nous voyons comment des partenaires sociaux tels que <strong>Forena<\/strong> (anciennement Sowepo) contribuent \u00e0 la <strong>durabilit\u00e9 soci\u00e9tale<\/strong>. \u00ab Nous travaillons avec des entreprises adapt\u00e9es pour offrir un travail significatif \u00e0 des personnes \u00e9loign\u00e9es du march\u00e9 du travail, \u00bb raconte Melissa. \u00ab\u00a0Cela renforce nos processus et notre mission sociale.\u00a0\u00bb<\/p>\n<h2>3. Utilisez la technologie comme moteur de durabilit\u00e9<\/h2>\n<p><strong>Crisp<\/strong> n&rsquo;utilise pas la technologie comme gadget, mais comme fondement. En permettant aux clients de commander d&rsquo;abord puis d&rsquo;acheter par la suite, ils minimisent le gaspillage. \u00ab Toute la nourriture que nous achetons est consomm\u00e9e, \u00bb d\u00e9clare Tom. \u00ab Notre technologie pr\u00e9dit la demande et l&rsquo;offre avec pr\u00e9cision et s&rsquo;adapte de mani\u00e8re flexible aux conditions m\u00e9t\u00e9o, aux saisons et aux r\u00e9coltes locales. \u00bb La logistique est \u00e9galement prise en compte : <strong>Crisp<\/strong> utilise des fourgonnettes de livraison \u00e9lectriques, une planification intelligente des itin\u00e9raires et un centre de distribution \u00e9co\u00e9nerg\u00e9tique qui r\u00e9utilise la chaleur r\u00e9siduelle. \u00ab La <strong>durabilit\u00e9<\/strong> n&rsquo;est pas un d\u00e9partement distinct chez nous. Elle est int\u00e9gr\u00e9e dans chaque syst\u00e8me et chaque processus. \u00bb<\/p>\n<p>Que les gens commandent leurs courses via une application chez <strong>Crisp<\/strong> n&rsquo;est pour eux qu&rsquo;un avantage: \u00ab Notre technologie et notre cha\u00eene courte nous permettent d&rsquo;\u00e9liminer les interm\u00e9diaires traditionnels et de proposer une offre aussi directe que possible du producteur \u00e0 l\u2019assiette. L&rsquo;application agit comme un point de connexion entre la demande nationale et l&rsquo;offre locale. Avec l&rsquo;offre de produits r\u00e9g\u00e9n\u00e9ratifs, la volatilit\u00e9 est plus impr\u00e9visible : l&rsquo;offre est moins pr\u00e9visible, car <a href=\"https:\/\/www.forbes.be\/nl\/the-barn-een-bedrijfsmodel-dat-biologische-voeding-betaalbaar-maakt-en-de-lokale-landbouw-ondersteunt\/\" target=\"_blank\" rel=\"noopener\">le producteur est litt\u00e9ralement d\u00e9pendant des conditions naturelles<\/a>. Le temps influence la r\u00e9colte et l&rsquo;agriculteur r\u00e9g\u00e9n\u00e9ratif n&rsquo;utilise pas d&rsquo;agents chimiques. De plus, tout ne pousse pas en \u00e9t\u00e9 ou en hiver, donc l&rsquo;assortiment est en rotation. L&rsquo;offre est donc moins certaine.\u00a0\u00bb<\/p>\n<h2>4. Osez montrer les imperfections dans votre communication<\/h2>\n<p>La transparence est une force, pas une faiblesse. \u00ab\u00a0Nous sommes maintenant \u00e0 70 % d&#8217;emballages recycl\u00e9s et visons 100 % d&rsquo;ici 2030,\u00a0\u00bb dit <strong>Melissa<\/strong>, de <strong>Purasana<\/strong>. \u00ab\u00a0En \u00e9tant ouvert \u00e0 ce sujet, nous cr\u00e9ons la confiance aupr\u00e8s de nos clients et en interne avec nos \u00e9quipes.\u00a0\u00bb Purasana partage non seulement des succ\u00e8s, mais aussi des d\u00e9fis. \u00ab Nous sommes ouverts sur, par exemple, la complexit\u00e9 de trouver un PET recycl\u00e9 (PET : poly\u00e9thyl\u00e8ne t\u00e9r\u00e9phtalate, un type de plastique couramment utilis\u00e9 dans les bouteilles et emballages alimentaires, ndlr)\u00a0de haute qualit\u00e9 qui respecte \u00e9galement les normes de s\u00e9curit\u00e9 alimentaire, \u00bb raconte <strong>Melissa<\/strong>. \u00ab\u00a0Cela rend notre approche cr\u00e9dible.\u00a0\u00bb<\/p>\n<figure id=\"attachment_8508\" aria-describedby=\"caption-attachment-8508\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8508 size-large\" src=\"https:\/\/www.forbes.be\/nl\/wp-content\/uploads\/2025\/04\/vision-healthcare-belgium-portraits-web-28-683x1024.jpg\" alt=\"\" width=\"683\" height=\"1024\" \/><figcaption id=\"caption-attachment-8508\" class=\"wp-caption-text\">Melissa De Lombaerde, coordinatrice de la durabilit\u00e9 chez Purasana<\/figcaption><\/figure>\n<h2>5. Int\u00e9grez la durabilit\u00e9 dans toute l&rsquo;organisation<\/h2>\n<p>Chez <strong>Purasana<\/strong>, la <strong>durabilit\u00e9<\/strong> est int\u00e9gr\u00e9e dans l&rsquo;ensemble des op\u00e9rations de l&rsquo;entreprise : un groupe de travail interne analyse en permanence o\u00f9 des am\u00e9liorations sont possibles. \u00ab\u00a0Nous encourageons des changements mineurs et structurels,\u00a0\u00bb explique Melissa. \u00ab\u00a0Des optimisations logistiques \u00e0 l&rsquo;organisation de journ\u00e9es \u00e0 v\u00e9lo pour le travail : tout compte.\u00a0\u00bb<\/p>\n<p><strong>Crisp<\/strong>, \u00e9galement, met l&rsquo;accent sur la culture : la <strong>durabilit\u00e9<\/strong> est une responsabilit\u00e9 que partagent tous les \u00e9quipes. Et chez <strong>Paveau<\/strong>, cela commence d\u00e8s la conception du produit : leurs verres sont r\u00e9utilisables, \u00e9l\u00e9gants et destin\u00e9s \u00e0 inspirer les consommateurs \u00e0 \u00eatre fiers de leur choix durable.<\/p>\n<h2>6. Fixez des objectifs clairs et mesurables et suivez-les<\/h2>\n<p>Des objectifs concrets aident \u00e0 maintenir le cap et \u00e0 mesurer les progr\u00e8s. Pour <strong>Crisp<\/strong>, la certification<strong> B Corp<\/strong> a \u00e9t\u00e9 un catalyseur. \u201cElle nous a permis de pr\u00e9ciser explicitement notre objectif d&rsquo;agriculture r\u00e9g\u00e9n\u00e9ratrice : d&rsquo;ici 2030, 30% de nos l\u00e9gumes et fruits devront \u00eatre cultiv\u00e9s r\u00e9g\u00e9n\u00e9rativement,\u201d dit Tom. <strong>Purasana<\/strong> relie les objectifs \u00e0 la nouvelle directive europ\u00e9enne PPWR (R\u00e9glementation des Emballages et D\u00e9chets d&rsquo;Emballages) et vise \u00e0 passer enti\u00e8rement aux emballages recycl\u00e9s d&rsquo;ici 2030. \u201cNous combinons cela avec des points de contr\u00f4le interm\u00e9diaires,\u201d dit Melissa.<\/p>\n<h2>7. Utilisez la durabilit\u00e9 comme levier de fid\u00e9lit\u00e9 \u00e0 la marque et de talent<\/h2>\n<p>Chez <strong>Crisp<\/strong>, plus de 85% des clients reviennent pour des achats r\u00e9p\u00e9t\u00e9s. \u201cNos clients reviennent pour le go\u00fbt, la fra\u00eecheur et la confiance,\u201d d\u00e9clare Tom. \u201cIls savent que nous faisons des choix conscients.\u201d La <strong>durabilit\u00e9<\/strong> fonctionne aussi comme un aimant \u00e0 talents. \u201cCela aide \u00e0 attirer des personnes exceptionnelles qui souhaitent contribuer \u00e0 b\u00e2tir une entreprise tourn\u00e9e vers l&rsquo;avenir,\u201d d\u00e9clare Tom. <strong>Paveau<\/strong> conna\u00eet une exp\u00e9rience similaire : \u201cNos clients \u2013 et aussi les collaborations \u2013 viennent souvent de valeurs partag\u00e9es,\u201d dit Isabelle.<\/p>\n<h2>8. Commencez petit, mais concr\u00e8tement et pers\u00e9v\u00e9rez<\/h2>\n<p>\u201cEntreprendre de <strong>mani\u00e8re durable<\/strong> n&rsquo;est pas un sprint, c&rsquo;est un parcours,\u201d d\u00e9clare Melissa. \u201cCommencez l\u00e0 o\u00f9 vous pouvez avoir un <strong>impact<\/strong> : emballages, transport, \u00e9nergie ou partenariat avec des partenaires locaux.\u201d <strong>Isabelle<\/strong>, de <strong>Paveau<\/strong> souligne l&rsquo;importance de chaque \u00e9tape. \u201cVous n&rsquo;avez pas besoin d&rsquo;\u00eatre parfait imm\u00e9diatement. Choisissez quelque chose de petit, mais faites-le de mani\u00e8re approfondie. Et assurez-vous que cela soit en ligne avec votre mission.\u201d<\/p>\n<figure id=\"attachment_8510\" aria-describedby=\"caption-attachment-8510\" style=\"width: 683px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8510 size-large\" src=\"https:\/\/www.forbes.be\/nl\/wp-content\/uploads\/2025\/04\/tom-peeters-ceo-3-683x1024.jpeg\" alt=\"\" width=\"683\" height=\"1024\" \/><figcaption id=\"caption-attachment-8510\" class=\"wp-caption-text\">Tom Peeters, CEO Crisp<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Que signifie r\u00e9ellement entreprendre de mani\u00e8re durable en 2025 ? Comment \u00e9viter de se limiter \u00e0 une promesse vague ou \u00e0 un vernis vert, et comment faire de la durabilit\u00e9 un avantage strat\u00e9gique \u2013 \u00e0 la fois \u00e9cologique, social et \u00e9conomique ?<\/p>\n","protected":false},"author":13,"featured_media":10477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1,19,49,14,27],"tags":[],"class_list":["post-10478","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualite","category-entrepreneurs","category-environnement","category-innovation","category-societe"],"acf":[],"_yoast_wpseo_title":"Comment les entreprises peuvent devenir plus durables","_yoast_wpseo_metadesc":"D\u00e9couvrez comment rendre votre entreprise \u00e9cologiquement, socialement et \u00e9conomiquement durable.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment les entreprises peuvent devenir plus durables<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment rendre votre entreprise \u00e9cologiquement, socialement et \u00e9conomiquement durable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment les entreprises peuvent devenir plus durables\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment rendre votre entreprise \u00e9cologiquement, socialement et \u00e9conomiquement durable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-20T07:27:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T12:40:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/8507-tom-peeters-ceo-2-e1747831217245.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1005\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daphne Dorgelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daphne Dorgelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/\"},\"author\":{\"name\":\"Daphne Dorgelo\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/7d78f899f595d5e9c1eb19ffe4d36b83\"},\"headline\":\"8 fa\u00e7ons pour les entrepreneurs de rendre leur entreprise plus durable\",\"datePublished\":\"2025-05-20T07:27:42+00:00\",\"dateModified\":\"2025-05-21T12:40:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/\"},\"wordCount\":1704,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/8507-tom-peeters-ceo-2-e1747831217245.png\",\"articleSection\":[\"Actualit\u00e9s\",\"Entrepreneurs\",\"Environnement\",\"Innovation\",\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/\",\"name\":\"Comment les entreprises peuvent devenir plus durables\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/8507-tom-peeters-ceo-2-e1747831217245.png\",\"datePublished\":\"2025-05-20T07:27:42+00:00\",\"dateModified\":\"2025-05-21T12:40:32+00:00\",\"description\":\"D\u00e9couvrez comment rendre votre entreprise \u00e9cologiquement, socialement et \u00e9conomiquement durable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/8507-tom-peeters-ceo-2-e1747831217245.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/8507-tom-peeters-ceo-2-e1747831217245.png\",\"width\":1920,\"height\":1005,\"caption\":\"Tom Peeters, CEO Crisp, de eerste supermarkt in Vlaanderen met een B Corp-certificaat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/facons-entrepreneurs-entreprise-durable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8 fa\u00e7ons pour les entrepreneurs de rendre leur entreprise plus durable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/7d78f899f595d5e9c1eb19ffe4d36b83\",\"name\":\"Daphne Dorgelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/4B1A6779-2-scaled-e1704882544546-150x150.jpg\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/4B1A6779-2-scaled-e1704882544546-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/4B1A6779-2-scaled-e1704882544546-150x150.jpg\",\"caption\":\"Daphne Dorgelo\"},\"description\":\"Daphne Dorgelo (1996) travaille chaque semaine pour Forbes, o\u00f9 elle r\u00e9dige des articles sur le style de vie luxueux, le leadership, l'innovation, les tendances et, bien s\u00fbr, les entrepreneurs belges inspirants. Sa passion pour le journalisme et les m\u00e9dias s'est manifest\u00e9e d\u00e8s son plus jeune \u00e2ge. Apr\u00e8s avoir obtenu une licence en information aux Pays-Bas, elle s'est install\u00e9e dans la ville belge du diamant il y a six ans, apr\u00e8s avoir obtenu un master en journalisme \u00e0 la KU Leuven d'Anvers. Cela fait maintenant huit ans qu'elle \u00e9crit en tant que pigiste pour divers magazines, dont quatre ans pour des magazines de style de vie belges tels que L'OFFICIEL, Fifty &amp; Me et ELLE.\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/daphne-dorgelolofficiel-be\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment les entreprises peuvent devenir plus durables","description":"D\u00e9couvrez comment rendre votre entreprise \u00e9cologiquement, socialement et \u00e9conomiquement durable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment les entreprises peuvent devenir plus durables","og_description":"D\u00e9couvrez comment rendre votre entreprise \u00e9cologiquement, socialement et \u00e9conomiquement durable.","og_url":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2025-05-20T07:27:42+00:00","article_modified_time":"2025-05-21T12:40:32+00:00","og_image":[{"width":1920,"height":1005,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/8507-tom-peeters-ceo-2-e1747831217245.png","type":"image\/png"}],"author":"Daphne Dorgelo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Daphne Dorgelo","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/"},"author":{"name":"Daphne Dorgelo","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/7d78f899f595d5e9c1eb19ffe4d36b83"},"headline":"8 fa\u00e7ons pour les entrepreneurs de rendre leur entreprise plus durable","datePublished":"2025-05-20T07:27:42+00:00","dateModified":"2025-05-21T12:40:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/"},"wordCount":1704,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/8507-tom-peeters-ceo-2-e1747831217245.png","articleSection":["Actualit\u00e9s","Entrepreneurs","Environnement","Innovation","Soci\u00e9t\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/","url":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/","name":"Comment les entreprises peuvent devenir plus durables","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/8507-tom-peeters-ceo-2-e1747831217245.png","datePublished":"2025-05-20T07:27:42+00:00","dateModified":"2025-05-21T12:40:32+00:00","description":"D\u00e9couvrez comment rendre votre entreprise \u00e9cologiquement, socialement et \u00e9conomiquement durable.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/8507-tom-peeters-ceo-2-e1747831217245.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/05\/8507-tom-peeters-ceo-2-e1747831217245.png","width":1920,"height":1005,"caption":"Tom Peeters, CEO Crisp, de eerste supermarkt in Vlaanderen met een B Corp-certificaat"},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/facons-entrepreneurs-entreprise-durable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"8 fa\u00e7ons pour les entrepreneurs de rendre leur entreprise plus durable"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/7d78f899f595d5e9c1eb19ffe4d36b83","name":"Daphne Dorgelo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/4B1A6779-2-scaled-e1704882544546-150x150.jpg","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/4B1A6779-2-scaled-e1704882544546-150x150.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/4B1A6779-2-scaled-e1704882544546-150x150.jpg","caption":"Daphne Dorgelo"},"description":"Daphne Dorgelo (1996) travaille chaque semaine pour Forbes, o\u00f9 elle r\u00e9dige des articles sur le style de vie luxueux, le leadership, l'innovation, les tendances et, bien s\u00fbr, les entrepreneurs belges inspirants. Sa passion pour le journalisme et les m\u00e9dias s'est manifest\u00e9e d\u00e8s son plus jeune \u00e2ge. Apr\u00e8s avoir obtenu une licence en information aux Pays-Bas, elle s'est install\u00e9e dans la ville belge du diamant il y a six ans, apr\u00e8s avoir obtenu un master en journalisme \u00e0 la KU Leuven d'Anvers. Cela fait maintenant huit ans qu'elle \u00e9crit en tant que pigiste pour divers magazines, dont quatre ans pour des magazines de style de vie belges tels que L'OFFICIEL, Fifty &amp; Me et ELLE.","url":"https:\/\/www.forbes.be\/fr\/author\/daphne-dorgelolofficiel-be\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=10478"}],"version-history":[{"count":2,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10478\/revisions"}],"predecessor-version":[{"id":10480,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10478\/revisions\/10480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/10477"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=10478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=10478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=10478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}