{"id":10708,"date":"2025-06-04T07:00:42","date_gmt":"2025-06-04T05:00:42","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=10708"},"modified":"2025-06-04T13:19:14","modified_gmt":"2025-06-04T11:19:14","slug":"sante-mentale-lever-le-tabou-repenser-lentreprise","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/","title":{"rendered":"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise"},"content":{"rendered":"<p><strong>Dans son livre confession <em>Int\u00e9rieur Nuit<\/em>, le c\u00e9l\u00e8bre journaliste fran\u00e7ais Nicolas Demorand <\/strong><strong>brise un tabou en r\u00e9v\u00e9lant publiquement son trouble bipolaire. En affirmant \u00ab je suis un <\/strong><strong>malade mental \u00bb, il s\u2019attaque au silence entourant les troubles psychiques, un sujet encore <\/strong><strong>trop stigmatis\u00e9. Interview de Christelle Tissot, la fondatrice de <a href=\"https:\/\/musae-tomorrow.com\/\" target=\"_blank\" rel=\"noopener\">M\u016bsae<\/a>, le premier m\u00e9dia soci\u00e9tal qui d\u00e9mocratise la sant\u00e9 mentale et accompagne les entreprises sur diff\u00e9rents sujets li\u00e9s \u00e0 la sant\u00e9 mentale avec des contenus de sensibilisation<\/strong><\/p>\n<p>Le t\u00e9moignage de <strong>Nicolas Demorand<\/strong> s\u2019inscrit dans un contexte o\u00f9 ces troubles touchent une personne sur huit dans le monde &#8211; pour celles et ceux diagnostiqu\u00e9s. Selon l\u2019<strong>OMS<\/strong>, malgr\u00e9 cette r\u00e9alit\u00e9, les moyens allou\u00e9s \u00e0 la sant\u00e9 mentale restent faibles : en moyenne, 2% des budgets nationaux de sant\u00e9 y sont consacr\u00e9s.<\/p>\n<div class=\"youtube-embed\" data-video_id=\"pmcnKYmxtlE\"><iframe loading=\"lazy\" title=\"Nicolas Demorand brise les tabous sur les maladies mentales\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/pmcnKYmxtlE?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>En Belgique, l\u2019augmentation de la consommation de <strong>psychotropes<\/strong> en est un indicateur alarmant. Un tiers de la population vivra un \u00e9pisode de <strong>d\u00e9stabilisation mentale<\/strong> au cours de sa vie. Le travail est souvent un facteur aggravant, impliqu\u00e9 dans 30 \u00e0 50% des cas de <strong>d\u00e9tresse psychologique<\/strong>. Face \u00e0 ce constat, les entreprises ont un r\u00f4le crucial \u00e0 jouer : celui de reconna\u00eetre, pr\u00e9venir et accompagner les <strong>troubles psychiques<\/strong> de leurs collaborateurs.<\/p>\n<p><strong>Forbes.be \u2013 Comment d\u00e9finissez-vous la sant\u00e9 mentale ?<\/strong><br \/>\n<strong>Christelle Tissot &#8211;<\/strong> Selon l\u2019<strong>Organisation Mondiale de la Sant\u00e9<\/strong>, la <strong>sant\u00e9 mentale<\/strong> est \u00ab un \u00e9tat de bien-\u00eatre dans lequel une personne peut se r\u00e9aliser, surmonter les tensions normales de la vie, accomplir un travail productif et contribuer \u00e0 la vie de sa communaut\u00e9. \u00bb. Cette d\u00e9finition met surtout en avant une vision positive de la <strong>sant\u00e9 mentale<\/strong>, avec laquelle je suis en partie en d\u00e9saccord. En r\u00e9alit\u00e9, la <strong>sant\u00e9 mentale<\/strong> est un ph\u00e9nom\u00e8ne beaucoup plus dynamique, complexe et mouvant. Elle existe le long d\u2019un continuum influenc\u00e9 par de nombreux facteurs tels que la g\u00e9n\u00e9tique, l\u2019\u00e9ducation, l\u2019environnement social et professionnel, etc. Elle \u00e9volue tout au long de la vie, oscillant entre \u00e9quilibre et fragilit\u00e9 selon les contextes.<\/p>\n<figure id=\"attachment_10714\" aria-describedby=\"caption-attachment-10714\" style=\"width: 1707px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10714\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-scaled.jpg\" alt=\"\" width=\"1707\" height=\"2560\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-scaled.jpg 1707w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-200x300.jpg 200w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-683x1024.jpg 683w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-768x1152.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-1024x1536.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-1365x2048.jpg 1365w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-696x1044.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-1068x1602.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-1920x2880.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/christelle-tissot-600x900.jpg 600w\" sizes=\"auto, (max-width: 1707px) 100vw, 1707px\" \/><figcaption id=\"caption-attachment-10714\" class=\"wp-caption-text\">Christelle Tissot \u00a9 DR<\/figcaption><\/figure>\n<p><strong>&#8211; Le travail est-il, selon vous, une source importante d\u2019instabilit\u00e9 psychique ?<\/strong><br \/>\n<strong>&#8211; <\/strong>Le<strong> travail<\/strong> peut effectivement \u00eatre une source d\u2019instabilit\u00e9 psychique, mais il peut aussi constituer une ressource essentielle pour la <strong>sant\u00e9 mentale<\/strong>. La <strong>philosophe Hannah Arendt<\/strong> identifie trois fonctions fondamentales du travail qui participent \u00e0 notre <strong>\u00e9quilibre psychique<\/strong>. D\u2019abord, il nous permet de subvenir \u00e0 nos besoins, en garantissant un revenu et une certaine dignit\u00e9. Ensuite, il nous offre une forme d\u2019accomplissement personnel, une routine structurante et des interactions sociales. Enfin, lorsqu\u2019il s\u2019exerce dans de bonnes conditions, le travail nous donne la possibilit\u00e9 d\u2019avoir un impact, que ce soit au sein de l\u2019organisation ou parfois sur le monde, ce qui vient renforcer notre <strong>bien-\u00eatre mental<\/strong>. Mais \u00e0 l\u2019inverse, un environnement de travail toxique \u2014 marqu\u00e9 par le manque de reconnaissance, la surcharge, l\u2019injustice, la pr\u00e9carit\u00e9 ou l\u2019isolement \u2014 peut devenir un facteur majeur de <strong>d\u00e9t\u00e9rioration psychique<\/strong>. Ces situations peuvent mener \u00e0 des troubles comme le burn-out ou la d\u00e9pression, souvent accompagn\u00e9s de stigmatisation et d\u2019exclusion. Or, le <strong>travail<\/strong> occupe une place centrale dans nos vies, au m\u00eame titre que nos relations personnelles, et joue un r\u00f4le social fondamental. \u00catre en bonne <strong>sant\u00e9 mentale<\/strong> peut favoriser une plus grande productivit\u00e9, mais il est essentiel de penser cette productivit\u00e9 comme la cons\u00e9quence du bien-\u00eatre, et non comme sa condition.<\/p>\n<p><strong>&#8211; Quel r\u00f4le l\u2019entreprise doit-elle jouer en mati\u00e8re de sant\u00e9 mentale ? Quels sont ses<\/strong><br \/>\n<strong>leviers ?<\/strong><br \/>\n<strong>&#8211;<\/strong> L\u2019<strong>entreprise<\/strong> a une responsabilit\u00e9 forte en mati\u00e8re de sant\u00e9 mentale, au m\u00eame titre qu\u2019elle est tenue d\u2019assurer la s\u00e9curit\u00e9 physique de ses salari\u00e9s. Elle doit cr\u00e9er un cadre protecteur, bienveillant et propice au dialogue. Cela commence par l\u2019adoption d\u2019un r\u00f4le actif : selon le cabinet Empreinte, sp\u00e9cialis\u00e9 en qualit\u00e9 de vie au travail et en pr\u00e9vention des risques psychosociaux, 59 % des salari\u00e9s estiment que la <strong>sant\u00e9 mentale<\/strong> devrait \u00eatre prise en charge par l\u2019<strong>entreprise<\/strong>. Pour y parvenir, plusieurs leviers existent. Mettre en place une organisation favorable est essentiel. Cela implique la cr\u00e9ation d\u2019espaces de discussion, l\u2019\u00e9laboration de politiques internes claires et un engagement sinc\u00e8re de la direction. La sensibilisation joue aussi un r\u00f4le cl\u00e9 : conf\u00e9rences, ateliers, formation des managers \u00e0 la d\u00e9tection des signaux de d\u00e9tresse psychique sont autant d\u2019actions possibles. Offrir des ressources concr\u00e8tes, telles que des <strong>psychologues du travail<\/strong>, des lignes d\u2019\u00e9coute ou des cellules de soutien, constitue un autre pilier important. L\u2019entreprise doit \u00e9galement s\u2019attaquer aux in\u00e9galit\u00e9s, notamment au \u201cworry gap\u201d \u2014 cet \u00e9cart d\u2019inqui\u00e9tude entre les femmes et les hommes, qui reste significatif. Elle a un r\u00f4le \u00e0 jouer dans la d\u00e9stigmatisation des <strong>troubles psychiques au travail<\/strong>, en lib\u00e9rant la parole, en donnant une voix aux personnes concern\u00e9es et en normalisant les parcours de soins ou de r\u00e9tablissement. Il est crucial de rappeler que <strong>handicap psychique<\/strong> et travail ne font pas n\u00e9cessairement mauvais m\u00e9nage, d\u2019autant plus que 80 % des handicaps sont invisibles. Enfin, favoriser l\u2019\u00e9quilibre entre vie professionnelle et vie personnelle, \u00e0 travers des am\u00e9nagements du temps ou des t\u00e2ches \u2014 notamment en contexte de <strong>t\u00e9l\u00e9travail<\/strong> \u2014 est une mesure concr\u00e8te et n\u00e9cessaire. Le <strong>travail<\/strong>, loin d\u2019\u00eatre uniquement un facteur de risque, peut aussi devenir un moteur de reconstruction. Il peut aider \u00e0 se r\u00e9tablir et \u00e0 retrouver une estime de soi apr\u00e8s une p\u00e9riode de fragilit\u00e9 psychique.<\/p>\n<figure id=\"attachment_10716\" aria-describedby=\"caption-attachment-10716\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10716\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-scaled.jpg 2560w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-300x200.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-1024x683.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-768x512.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-1536x1024.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-2048x1365.jpg 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-696x464.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-1068x712.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-1920x1280.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2258788941-600x400.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-10716\" class=\"wp-caption-text\">\u00a9 DR\/Shutterstock.com<\/figcaption><\/figure>\n<p><strong>&#8211; Peut-on imaginer un nouveau mod\u00e8le d\u2019entreprise centr\u00e9 sur l\u2019humain et le bien-\u00eatre <\/strong><strong>? Est-ce compatible avec la rentabilit\u00e9 ?<\/strong><br \/>\n<strong>&#8211;<\/strong> Absolument. Miser uniquement sur la performance imm\u00e9diate est une vision \u00e0 court terme. \u00c0 l\u2019inverse, investir dans les personnes, leur avenir, leur bien-\u00eatre et leur s\u00e9curit\u00e9 psychologique constitue un levier de r\u00e9ussite durable. La souffrance au travail est souvent r\u00e9v\u00e9latrice de dysfonctionnements organisationnels : mauvaise communication, charge excessive, isolement, discrimination ou absence de vision commune. Ce sont des sympt\u00f4mes d\u2019un d\u00e9s\u00e9quilibre structurel. Repenser l\u2019entreprise autour de valeurs humaines permet non seulement de mieux travailler ensemble, mais aussi d\u2019am\u00e9liorer la performance collective. Une culture d\u2019entreprise inclusive, bienveillante et collaborative contribue \u00e0 pr\u00e9venir les troubles psychiques, \u00e0 fid\u00e9liser les talents et \u00e0 renforcer l\u2019engagement. Mettre l\u2019humain au c\u0153ur de la strat\u00e9gie, c\u2019est finalement faire le choix d\u2019un mod\u00e8le plus r\u00e9silient, plus juste, et \u00e0 terme\u2026 plus rentable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans son livre confession Int\u00e9rieur Nuit, le c\u00e9l\u00e8bre journaliste fran\u00e7ais Nicolas Demorand brise un tabou en r\u00e9v\u00e9lant publiquement son trouble bipolaire. En affirmant \u00ab je suis un malade mental \u00bb, il s\u2019attaque au silence entourant les troubles psychiques, un sujet encore trop stigmatis\u00e9. Interview de Christelle Tissot, la fondatrice de M\u016bsae, le premier m\u00e9dia soci\u00e9tal [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":10715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[20,27],"tags":[],"class_list":["post-10708","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sante","category-societe"],"acf":[],"_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"Sant\u00e9 mentale et entreprise : Christelle Tissot appelle \u00e0 briser les tabous et repenser le travail comme levier de bien-\u00eatre, au-del\u00e0 de la seule performance.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise | Forbes Belgique<\/title>\n<meta name=\"description\" content=\"Sant\u00e9 mentale et entreprise : Christelle Tissot appelle \u00e0 briser les tabous et repenser le travail comme levier de bien-\u00eatre, au-del\u00e0 de la seule performance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise | Forbes Belgique\" \/>\n<meta property=\"og:description\" content=\"Sant\u00e9 mentale et entreprise : Christelle Tissot appelle \u00e0 briser les tabous et repenser le travail comme levier de bien-\u00eatre, au-del\u00e0 de la seule performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-04T05:00:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T11:19:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2223351467-scaled-e1749035940754.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claire Berticat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claire Berticat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/\"},\"author\":{\"name\":\"Claire Berticat\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/27e9fb8bca0797792f8a073f754c53f4\"},\"headline\":\"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise\",\"datePublished\":\"2025-06-04T05:00:42+00:00\",\"dateModified\":\"2025-06-04T11:19:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/\"},\"wordCount\":1147,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/shutterstock-2223351467-scaled-e1749035940754.jpg\",\"articleSection\":[\"Sant\u00e9\",\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/\",\"name\":\"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise | Forbes Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/shutterstock-2223351467-scaled-e1749035940754.jpg\",\"datePublished\":\"2025-06-04T05:00:42+00:00\",\"dateModified\":\"2025-06-04T11:19:14+00:00\",\"description\":\"Sant\u00e9 mentale et entreprise : Christelle Tissot appelle \u00e0 briser les tabous et repenser le travail comme levier de bien-\u00eatre, au-del\u00e0 de la seule performance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/shutterstock-2223351467-scaled-e1749035940754.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/shutterstock-2223351467-scaled-e1749035940754.jpg\",\"width\":2560,\"height\":1340,\"caption\":\"\u00a9\u00a0DR\\\/Shutterstock.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/sante-mentale-lever-le-tabou-repenser-lentreprise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/27e9fb8bca0797792f8a073f754c53f4\",\"name\":\"Claire Berticat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7e25323e2731e3dcf1962eca1137cacc6924cdb54bbe6ddabae40b271d3de5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7e25323e2731e3dcf1962eca1137cacc6924cdb54bbe6ddabae40b271d3de5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f7e25323e2731e3dcf1962eca1137cacc6924cdb54bbe6ddabae40b271d3de5?s=96&d=mm&r=g\",\"caption\":\"Claire Berticat\"},\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/claire-berticat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise | Forbes Belgique","description":"Sant\u00e9 mentale et entreprise : Christelle Tissot appelle \u00e0 briser les tabous et repenser le travail comme levier de bien-\u00eatre, au-del\u00e0 de la seule performance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/","og_locale":"fr_FR","og_type":"article","og_title":"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise | Forbes Belgique","og_description":"Sant\u00e9 mentale et entreprise : Christelle Tissot appelle \u00e0 briser les tabous et repenser le travail comme levier de bien-\u00eatre, au-del\u00e0 de la seule performance.","og_url":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2025-06-04T05:00:42+00:00","article_modified_time":"2025-06-04T11:19:14+00:00","og_image":[{"width":2560,"height":1340,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2223351467-scaled-e1749035940754.jpg","type":"image\/jpeg"}],"author":"Claire Berticat","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Claire Berticat","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/"},"author":{"name":"Claire Berticat","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/27e9fb8bca0797792f8a073f754c53f4"},"headline":"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise","datePublished":"2025-06-04T05:00:42+00:00","dateModified":"2025-06-04T11:19:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/"},"wordCount":1147,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2223351467-scaled-e1749035940754.jpg","articleSection":["Sant\u00e9","Soci\u00e9t\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/","url":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/","name":"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise | Forbes Belgique","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2223351467-scaled-e1749035940754.jpg","datePublished":"2025-06-04T05:00:42+00:00","dateModified":"2025-06-04T11:19:14+00:00","description":"Sant\u00e9 mentale et entreprise : Christelle Tissot appelle \u00e0 briser les tabous et repenser le travail comme levier de bien-\u00eatre, au-del\u00e0 de la seule performance.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2223351467-scaled-e1749035940754.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/06\/shutterstock-2223351467-scaled-e1749035940754.jpg","width":2560,"height":1340,"caption":"\u00a9\u00a0DR\/Shutterstock.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/sante-mentale-lever-le-tabou-repenser-lentreprise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Sant\u00e9 mentale : lever le tabou, repenser l\u2019entreprise"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/27e9fb8bca0797792f8a073f754c53f4","name":"Claire Berticat","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5f7e25323e2731e3dcf1962eca1137cacc6924cdb54bbe6ddabae40b271d3de5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f7e25323e2731e3dcf1962eca1137cacc6924cdb54bbe6ddabae40b271d3de5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f7e25323e2731e3dcf1962eca1137cacc6924cdb54bbe6ddabae40b271d3de5?s=96&d=mm&r=g","caption":"Claire Berticat"},"url":"https:\/\/www.forbes.be\/fr\/author\/claire-berticat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=10708"}],"version-history":[{"count":5,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10708\/revisions"}],"predecessor-version":[{"id":10725,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/10708\/revisions\/10725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/10715"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=10708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=10708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=10708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}