{"id":12361,"date":"2025-09-15T12:39:21","date_gmt":"2025-09-15T10:39:21","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=12361"},"modified":"2025-09-15T12:46:02","modified_gmt":"2025-09-15T10:46:02","slug":"gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/","title":{"rendered":"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles"},"content":{"rendered":"<p><strong>L&rsquo;exposition \u00ab\u00a0Gaza: Stories of Hope and Resilience\u00a0\u00bb, lanc\u00e9e \u00e0 Bruxelles par le Programme alimentaire mondial (PAM) et l&rsquo;Union europ\u00e9enne (UE), pr\u00e9sente les \u0153uvres poignantes de l\u2019artiste palestinien Ahmed Muhanna. Cette tourn\u00e9e europ\u00e9enne, soutenue par Alia Zaki (Forbes 30U30 Middle East 2024) vise \u00e0 sensibiliser le public \u00e0 la crise humanitaire \u00e0 Gaza par le prisme de l\u2019art contemporain.<\/strong><\/p>\n<p>Du 15 au 18 septembre 2025, la <strong>Place de la Monnaie<\/strong> \u00e0 Bruxelles a accueilli le lancement d\u2019une exposition hors normes : \u00ab\u00a0<strong>Gaza: Stories of Hope and Resilience<\/strong>\u00ab\u00a0. Organis\u00e9e par le <a href=\"https:\/\/fr.wfp.org\/\" target=\"_blank\" rel=\"noopener\"><strong>Programme alimentaire mondial (PAM)<\/strong><\/a> en partenariat avec l\u2019Union europ\u00e9enne, cette exposition itin\u00e9rante s\u2019inscrit dans une campagne de visibilit\u00e9 visant \u00e0 attirer l\u2019attention sur la crise humanitaire qui s\u00e9vit \u00e0 <strong>Gaza<\/strong>.<\/p>\n<p>Ce projet met en lumi\u00e8re le quotidien boulevers\u00e9 de 2,3 millions de personnes, tout en soulignant l\u2019impact des op\u00e9rations humanitaires soutenues par l\u2019<strong>UE<\/strong> et le <strong>PAM<\/strong>. Comme l\u2019a rappel\u00e9 <strong>Antoine Renard<\/strong>, Directeur national du <strong>PAM<\/strong> pour la <strong>Palestine<\/strong> : \u00ab <em>Les chiffres \u00e0 <strong>Gaza<\/strong> sont alarmants : le nombre de personnes dans le besoin, le nombre de morts, le nombre de familles qui passent des jours sans nourriture. Derri\u00e8re chaque statistique se trouvent des \u00eatres humains, et ces \u0153uvres d&rsquo;art leur donnent une voix.<\/em> \u00bb<\/p>\n<h2>Ahmed Muhanna : l\u2019art comme m\u00e9moire de guerre<\/h2>\n<p>L\u2019<strong>artiste Ahmed Muhanna<\/strong>, n\u00e9 en 1984 \u00e0 <strong>Deir Al-Balah<\/strong> (<strong>Gaza<\/strong>) et dipl\u00f4m\u00e9 de l\u2019Universit\u00e9 Al-Aqsa, signe ici sa premi\u00e8re exposition solo en Europe. Priv\u00e9 de mat\u00e9riel artistique en raison du conflit, Muhanna a transform\u00e9 les cartons d\u2019aide alimentaire du <strong>PAM<\/strong> en toiles de t\u00e9moignage.<\/p>\n<figure id=\"attachment_12366\" aria-describedby=\"caption-attachment-12366\" style=\"width: 318px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12366 size-full\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/wfp-eu-gaza-exhibition-3.jpg\" alt=\"\" width=\"318\" height=\"566\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/wfp-eu-gaza-exhibition-3.jpg 318w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/wfp-eu-gaza-exhibition-3-169x300.jpg 169w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><figcaption id=\"caption-attachment-12366\" class=\"wp-caption-text\">\u00a9 Ahmed Muhanna<\/figcaption><\/figure>\n<p>\u00ab<em> J&rsquo;ai commenc\u00e9 \u00e0 dessiner ce que je voyais et entendais chaque jour sur ces bo\u00eetes de nourriture comme un moyen de relier l&rsquo;espoir \u00e0 la douleur<\/em> \u00bb, confie-t-il. Il utilise des mat\u00e9riaux alternatifs (marc de caf\u00e9, plantes locales comme pigments) pour peindre la r\u00e9silience de <strong>Gaza<\/strong>. Plus de quarante \u0153uvres sont expos\u00e9es, accompagn\u00e9es de l\u00e9gendes manuscrites en arabe, de traductions, de bandes sonores immersives et d\u2019une interview vid\u00e9o de l\u2019artiste projet\u00e9e en continu.<\/p>\n<h2>Une tourn\u00e9e europ\u00e9enne \u00e0 fort impact symbolique<\/h2>\n<p>Transport\u00e9e dans un container de 62 m\u00e8tres carr\u00e9s con\u00e7u sp\u00e9cialement pour l\u2019occasion, l\u2019<strong>exposition<\/strong> est mobile et autonome. Elle parcourt six pays europ\u00e9ens jusqu\u2019au 23 octobre 2025. Apr\u00e8s <strong>Bruxelles<\/strong>, elle est pr\u00e9sent\u00e9e \u00e0 G\u00f6teborg, Malm\u00f6, Copenhague, Hambourg, Cologne, Maastricht, Leuven et Lille. Chaque \u00e9tape permet d\u2019ancrer la question humanitaire palestinienne dans l\u2019espace public europ\u00e9en et d\u2019inviter les visiteurs \u00e0 un contact direct avec l\u2019art et les r\u00e9cits de <strong>Gaza<\/strong>.<\/p>\n<h2>Alia Zaki : communication strat\u00e9gique et reconnaissance Forbes<\/h2>\n<p>\u00c0 seulement 27 ans, <a href=\"https:\/\/www.forbesmiddleeast.com\/lists\/30-under-30-2024\/alia-zaki\/\" target=\"_blank\" rel=\"noopener\"><strong>Alia Zaki<\/strong><\/a>, Responsable des Communications au<strong> PAM Palestine<\/strong>, joue un r\u00f4le cl\u00e9 dans cette exposition. Reconnue dans la liste <strong>Forbes Middle East 30 Under 30<\/strong> pour son impact social, elle coordonne la promotion m\u00e9diatique de l\u2019\u00e9v\u00e9nement \u00e0 l\u2019\u00e9chelle europ\u00e9enne. Forte d\u2019une exp\u00e9rience internationale acquise en \u00c9thiopie, en Turquie et au Bangladesh, elle a men\u00e9 des campagnes ayant permis de lever cinq millions de dollars pour Gaza.<\/p>\n<figure id=\"attachment_12363\" aria-describedby=\"caption-attachment-12363\" style=\"width: 2000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12363\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki.jpg\" alt=\"\" width=\"2000\" height=\"2000\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki.jpg 2000w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-300x300.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-1024x1024.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-150x150.jpg 150w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-768x768.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-1536x1536.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-696x696.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-1068x1068.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-1920x1920.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-600x600.jpg 600w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/alia-zaki-100x100.jpg 100w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><figcaption id=\"caption-attachment-12363\" class=\"wp-caption-text\">Alia Zaki \u00a9 DR<\/figcaption><\/figure>\n<p>Sa capacit\u00e9 \u00e0 tisser des liens entre les r\u00e9cits des familles palestiniennes, les activistes et le grand public donne une dimension humaine et strat\u00e9gique \u00e0 l\u2019exposition. Dans une interview \u00e0 UN News, elle alertait : \u00ab <em>La situation sur le terrain est alarmante. Les syst\u00e8mes alimentaires existants s&rsquo;effondrent.<\/em> \u00bb Son implication illustre la mont\u00e9e en puissance d\u2019une nouvelle g\u00e9n\u00e9ration de communicants humanitaires engag\u00e9s.<\/p>\n<h2>Une alliance strat\u00e9gique entre le PAM et l\u2019Union europ\u00e9enne<\/h2>\n<p>Le <strong>PAM<\/strong> et l\u2019<strong>Union europ\u00e9enne<\/strong> s\u2019appuient sur cette exposition pour mettre en lumi\u00e8re leur partenariat actif sur le terrain. Depuis octobre 2023, l\u2019UE a vers\u00e9 86 millions d\u2019euros au PAM pour soutenir les op\u00e9rations \u00e0 Gaza. Gr\u00e2ce \u00e0 ce soutien, des milliers de convois alimentaires ont \u00e9t\u00e9 achemin\u00e9s vers les zones les plus touch\u00e9es par la faim et la malnutrition.<\/p>\n<p>La <strong>Commissaire europ\u00e9enne Hadja Lahbib<\/strong> a salu\u00e9 cette initiative artistique : \u00ab<em> La situation humanitaire \u00e0 <strong>Gaza<\/strong> est au-del\u00e0 de l&rsquo;intol\u00e9rable \u2013 une dure r\u00e9alit\u00e9 d\u00e9peinte par l&rsquo;<strong>artiste Ahmed Muhanna<\/strong> sur les colis utilis\u00e9s pour la livraison d&rsquo;aide humanitaire. De la livraison de nourriture, ces bo\u00eetes livrent maintenant de l&rsquo;espoir.<\/em> \u00bb<\/p>\n<h2>L\u2019art comme levier de sensibilisation et de dialogue<\/h2>\n<p>Au-del\u00e0 de sa port\u00e9e documentaire, l\u2019exposition pose la question du r\u00f4le de l\u2019art dans les crises contemporaines. \u00c0 travers les \u0153uvres de <strong>Muhanna<\/strong>, le public europ\u00e9en acc\u00e8de \u00e0 une r\u00e9alit\u00e9 souvent lointaine et abstraite. L\u2019artiste, qui pratique \u00e9galement l\u2019art-th\u00e9rapie aupr\u00e8s d\u2019enfants, transforme la contrainte mat\u00e9rielle en expression artistique, la douleur en message d\u2019espoir.<\/p>\n<figure id=\"attachment_12369\" aria-describedby=\"caption-attachment-12369\" style=\"width: 468px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12369 size-full\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/wfp-eu-gaza-exhibition-2-1.jpg\" alt=\"\" width=\"468\" height=\"583\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/wfp-eu-gaza-exhibition-2-1.jpg 468w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/wfp-eu-gaza-exhibition-2-1-241x300.jpg 241w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><figcaption id=\"caption-attachment-12369\" class=\"wp-caption-text\">\u00a9 Ahmed Muhanna<\/figcaption><\/figure>\n<p>L\u2019exposition \u00ab\u00a0<strong>Gaza: Stories of Hope and Resilience<\/strong>\u00a0\u00bb n\u2019est pas seulement un \u00e9v\u00e9nement culturel. C\u2019est un acte de transmission, un pont entre les soci\u00e9t\u00e9s, une invitation \u00e0 \u00e9couter autrement ceux dont la voix est \u00e9touff\u00e9e. Elle ouvre une r\u00e9flexion sur la place de l\u2019art dans les strat\u00e9gies humanitaires et sur le pouvoir du r\u00e9cit visuel comme moteur de solidarit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;exposition \u00ab\u00a0Gaza: Stories of Hope and Resilience\u00a0\u00bb, lanc\u00e9e \u00e0 Bruxelles par le Programme alimentaire mondial (PAM) et l&rsquo;Union europ\u00e9enne (UE), pr\u00e9sente les \u0153uvres poignantes de l\u2019artiste palestinien Ahmed Muhanna. Cette tourn\u00e9e europ\u00e9enne, soutenue par Alia Zaki (Forbes 30U30 Middle East 2024) vise \u00e0 sensibiliser le public \u00e0 la crise humanitaire \u00e0 Gaza par le prisme [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":12368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1,27],"tags":[],"class_list":["post-12361","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualite","category-societe"],"acf":[],"_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"\u00c0 Bruxelles, l\u2019exposition \"Gaza: Stories of Hope and Resilience\" du PAM et de l\u2019UE d\u00e9voile les \u0153uvres poignantes d\u2019Ahmed Muhanna pour sensibiliser \u00e0 la crise humanitaire.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles | Forbes Belgique<\/title>\n<meta name=\"description\" content=\"\u00c0 Bruxelles, l\u2019exposition &quot;Gaza: Stories of Hope and Resilience&quot; du PAM et de l\u2019UE d\u00e9voile les \u0153uvres poignantes d\u2019Ahmed Muhanna pour sensibiliser \u00e0 la crise humanitaire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles | Forbes Belgique\" \/>\n<meta property=\"og:description\" content=\"\u00c0 Bruxelles, l\u2019exposition &quot;Gaza: Stories of Hope and Resilience&quot; du PAM et de l\u2019UE d\u00e9voile les \u0153uvres poignantes d\u2019Ahmed Muhanna pour sensibiliser \u00e0 la crise humanitaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T10:39:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T10:46:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"837\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin Boonen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin Boonen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/\"},\"author\":{\"name\":\"Martin Boonen\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/5e9af5383f8e0ffec564788f40ac92c8\"},\"headline\":\"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles\",\"datePublished\":\"2025-09-15T10:39:21+00:00\",\"dateModified\":\"2025-09-15T10:46:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/\"},\"wordCount\":895,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg\",\"articleSection\":[\"Actualit\u00e9s\",\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/\",\"name\":\"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles | Forbes Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg\",\"datePublished\":\"2025-09-15T10:39:21+00:00\",\"dateModified\":\"2025-09-15T10:46:02+00:00\",\"description\":\"\u00c0 Bruxelles, l\u2019exposition \\\"Gaza: Stories of Hope and Resilience\\\" du PAM et de l\u2019UE d\u00e9voile les \u0153uvres poignantes d\u2019Ahmed Muhanna pour sensibiliser \u00e0 la crise humanitaire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg\",\"width\":1600,\"height\":837,\"caption\":\"L'exposition \\\"Gaza: Stories of Hope and Resilience\\\" d\u00e9bute sa tourn\u00e9e europ\u00e9enne \u00e0 Bruxelles \u00a9 DR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/5e9af5383f8e0ffec564788f40ac92c8\",\"name\":\"Martin Boonen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/capture-decran-2024-11-15-a-093849-300x300-1-100x100.png\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/capture-decran-2024-11-15-a-093849-300x300-1-100x100.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/capture-decran-2024-11-15-a-093849-300x300-1-100x100.png\",\"caption\":\"Martin Boonen\"},\"description\":\"Martin Boonen est journaliste dipl\u00f4m\u00e9 de l'Institut de Journalisme de Bruxelles (2012). Il collabor\u00e9 avec de nombreuses r\u00e9dactions \u00e0 diff\u00e9rent niveau de responsabilit\u00e9 : journaliste, chef de rubrique, secr\u00e9taire de r\u00e9daction et r\u00e9dacteur en chef, tant sur le web que pour la presse imprim\u00e9e. Sp\u00e9cialis\u00e9 dans les startups et l'entrepreneuriat \u00e0 impact, il est devenu en 2025 r\u00e9dacteur en chef du site web de Forbes Belgique. Il est affili\u00e9 \u00e0 l'Organisation Mondiale de la Presse P\u00e9riodique depuis 2011.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/martin-boonen-61499951\\\/\"],\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/martin-boonen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles | Forbes Belgique","description":"\u00c0 Bruxelles, l\u2019exposition \"Gaza: Stories of Hope and Resilience\" du PAM et de l\u2019UE d\u00e9voile les \u0153uvres poignantes d\u2019Ahmed Muhanna pour sensibiliser \u00e0 la crise humanitaire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles | Forbes Belgique","og_description":"\u00c0 Bruxelles, l\u2019exposition \"Gaza: Stories of Hope and Resilience\" du PAM et de l\u2019UE d\u00e9voile les \u0153uvres poignantes d\u2019Ahmed Muhanna pour sensibiliser \u00e0 la crise humanitaire.","og_url":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2025-09-15T10:39:21+00:00","article_modified_time":"2025-09-15T10:46:02+00:00","og_image":[{"width":1600,"height":837,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg","type":"image\/jpeg"}],"author":"Martin Boonen","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Martin Boonen","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/"},"author":{"name":"Martin Boonen","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/5e9af5383f8e0ffec564788f40ac92c8"},"headline":"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles","datePublished":"2025-09-15T10:39:21+00:00","dateModified":"2025-09-15T10:46:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/"},"wordCount":895,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg","articleSection":["Actualit\u00e9s","Soci\u00e9t\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/","url":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/","name":"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles | Forbes Belgique","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg","datePublished":"2025-09-15T10:39:21+00:00","dateModified":"2025-09-15T10:46:02+00:00","description":"\u00c0 Bruxelles, l\u2019exposition \"Gaza: Stories of Hope and Resilience\" du PAM et de l\u2019UE d\u00e9voile les \u0153uvres poignantes d\u2019Ahmed Muhanna pour sensibiliser \u00e0 la crise humanitaire.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/09\/whatsapp-image-2025-09-14-at-124319-e1757933152686.jpeg","width":1600,"height":837,"caption":"L'exposition \"Gaza: Stories of Hope and Resilience\" d\u00e9bute sa tourn\u00e9e europ\u00e9enne \u00e0 Bruxelles \u00a9 DR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/gaza-dans-les-rues-deurope-lart-de-resister-expose-a-bruxelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Gaza dans les rues d\u2019Europe : l\u2019art de r\u00e9sister expos\u00e9 \u00e0 Bruxelles"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/5e9af5383f8e0ffec564788f40ac92c8","name":"Martin Boonen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2024-11-15-a-093849-300x300-1-100x100.png","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2024-11-15-a-093849-300x300-1-100x100.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2024-11-15-a-093849-300x300-1-100x100.png","caption":"Martin Boonen"},"description":"Martin Boonen est journaliste dipl\u00f4m\u00e9 de l'Institut de Journalisme de Bruxelles (2012). Il collabor\u00e9 avec de nombreuses r\u00e9dactions \u00e0 diff\u00e9rent niveau de responsabilit\u00e9 : journaliste, chef de rubrique, secr\u00e9taire de r\u00e9daction et r\u00e9dacteur en chef, tant sur le web que pour la presse imprim\u00e9e. Sp\u00e9cialis\u00e9 dans les startups et l'entrepreneuriat \u00e0 impact, il est devenu en 2025 r\u00e9dacteur en chef du site web de Forbes Belgique. Il est affili\u00e9 \u00e0 l'Organisation Mondiale de la Presse P\u00e9riodique depuis 2011.","sameAs":["https:\/\/www.linkedin.com\/in\/martin-boonen-61499951\/"],"url":"https:\/\/www.forbes.be\/fr\/author\/martin-boonen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/12361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=12361"}],"version-history":[{"count":3,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/12361\/revisions"}],"predecessor-version":[{"id":12370,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/12361\/revisions\/12370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/12368"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=12361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=12361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=12361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}