{"id":12702,"date":"2025-10-23T07:35:56","date_gmt":"2025-10-23T05:35:56","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=12702"},"modified":"2025-10-22T09:12:24","modified_gmt":"2025-10-22T07:12:24","slug":"la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/","title":{"rendered":"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9"},"content":{"rendered":"<p><strong>Longtemps per\u00e7ue comme une r\u00e9volution in\u00e9vitable, la voiture \u00e9lectrique semble aujourd\u2019hui traverser une zone de turbulences. Les constructeurs (europ\u00e9ens) plaident pour un ralentissement du calendrier europ\u00e9en, accusant une demande trop timide et un cadre r\u00e9glementaire d\u00e9connect\u00e9 du terrain. La transition, promise comme lin\u00e9aire et rapide, s\u2019av\u00e8re plus fragile qu\u2019esp\u00e9r\u00e9.<\/strong><\/p>\n<p>Pendant des ann\u00e9es, les salons automobiles ont \u00e9t\u00e9 le th\u00e9\u00e2tre d\u2019un optimisme \u00e9lectrique d\u00e9bordant. Les marques multipliaient les annonces, promettant une gamme 100% \u00e9lectrique \u00e0 l\u2019horizon 2030. Mais aujourd\u2019hui, si les acteurs du march\u00e9 continuent \u00e0 d\u00e9voiler des nouveaut\u00e9s \u00ab\u00a0branch\u00e9es\u00a0\u00bb, les discours changent de ton. <strong>Opel<\/strong> a d\u00e9j\u00e0 renonc\u00e9 \u00e0 son objectif de tout-\u00e9lectrique d\u00e8s 2028, <strong>Stellantis<\/strong> revoit ses ambitions \u00e0 la baisse, et <strong>BMW<\/strong> appelle \u00e0 repousser la neutralit\u00e9 carbone \u00e0 2050 plut\u00f4t qu\u2019\u00e0 2035. \u00ab<em> Les objectifs europ\u00e9ens doivent \u00eatre liss\u00e9s jusqu\u2019en 2050 plut\u00f4t qu\u2019en 2035, sous peine de voir l\u2019industrie automobile europ\u00e9enne diminuer de moiti\u00e9<\/em> \u00bb, pr\u00e9vient <strong>Oliver Zipse<\/strong>, CEO de <strong>BMW<\/strong>.<\/p>\n<p>M\u00eame son de cloche chez<strong> Jean-Philippe Imparato<\/strong>, patron de <strong>Stellantis Europe<\/strong> : \u00ab <em>Je peux vous dire que les objectifs 2035 ne sont pas atteignables. Le march\u00e9 risque de s\u2019\u00e9craser.<\/em> \u00bb<\/p>\n<p>Les dirigeants invoquent un argument cl\u00e9 : la demande ne suit pas. Les clients, frein\u00e9s par le prix, l\u2019autonomie, les infrastructures de recharge et les incertitudes fiscales, ne se ruent pas sur les mod\u00e8les \u00e0 batteries. \u00ab <em>Les clients nous disent que la vitesse que l\u2019on avait pr\u00e9vue est juste trop rapide. Il y a trois ans, les experts nous disaient que le march\u00e9 de l\u2019\u00e9lectrique serait \u00e0 30% en 2025. Nous sommes \u00e0 17% !<\/em> \u00bb, d\u00e9plore <strong>Xavier Martinet<\/strong>, CEO de <strong>Hyundai Motor Europe<\/strong>.<\/p>\n<figure id=\"attachment_13001\" aria-describedby=\"caption-attachment-13001\" style=\"width: 2250px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13001\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group.jpg\" alt=\"\" width=\"2250\" height=\"1500\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group.jpg 2250w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-300x200.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-1024x683.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-768x512.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-1536x1024.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-2048x1365.jpg 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-696x464.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-1068x712.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-1920x1280.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/oliver-zipse-bmw-group-600x400.jpg 600w\" sizes=\"auto, (max-width: 2250px) 100vw, 2250px\" \/><figcaption id=\"caption-attachment-13001\" class=\"wp-caption-text\">Oliver Zipse \u00a9 BMW Group<\/figcaption><\/figure>\n<p>\u00ab <em>Nous avons construit nos plans produits sur un sc\u00e9nario qui, \u00e0 l\u2019\u00e9poque, semblait r\u00e9aliste<\/em>, explique <strong>Florian Huettl<\/strong>, CEO d\u2019<strong>Opel<\/strong>. <em>Mais au fur et \u00e0 mesure, la probabilit\u00e9 de le voir se r\u00e9aliser a diminu\u00e9. Malgr\u00e9 une belle progression de l\u2019\u00e9lectrique, ce n\u2019est pas suffisant.<\/em> \u00bb<\/p>\n<h2>Un march\u00e9 qui cale, une politique qui s\u2019interroge<\/h2>\n<p>Face \u00e0 cette d\u00e9c\u00e9l\u00e9ration, l\u2019industrie en appelle d\u00e9sormais \u00e0 Bruxelles. La Commission europ\u00e9enne a accept\u00e9 de r\u00e9examiner \u00ab<em> le plus t\u00f4t possible<\/em> \u00bb l\u2019interdiction des <strong>moteurs thermiques<\/strong> pr\u00e9vue pour 2035. Une inflexion soutenue par Berlin : le <strong>chancelier Friedrich Merz<\/strong> r\u00e9clame une r\u00e9glementation plus \u00ab <em>souple et pragmatique<\/em> \u00bb.<br \/>\nLes constructeurs insistent : il ne s\u2019agit pas de renier la transition, mais d\u2019en adapter le tempo. Leurs investissements dans l\u2019<strong>\u00e9lectrique<\/strong> se poursuivent &#8211; et cela se voit au quotidien, avec un rythme effr\u00e9n\u00e9 de lancement de nouveaut\u00e9s ou de concepts proches de la production &#8211; mais le secteur craint que la marche forc\u00e9e impos\u00e9e par l\u2019UE ne le conduise dans le mur.<\/p>\n<h2>Le r\u00eave \u00e9lectrique des marques sportives s\u2019\u00e9vapore<\/h2>\n<p>Cette d\u00e9sillusion touche m\u00eame le sommet de la pyramide : les <a href=\"https:\/\/www.forbes.be\/fr\/mclaren-750s-lultime-signature-thermique-avant-lere-electrique\/\" target=\"_blank\" rel=\"noopener\">marques de luxe et de sport, cens\u00e9es incarner la vitrine technologique du tout-\u00e9lectrique<\/a>. L\u2019\u00e9motion m\u00e9canique, la l\u00e9g\u00e8ret\u00e9 et le bruit \u2013 composantes essentielles du plaisir automobile \u2013 se traduisent mal dans le monde du kilowattheure. Plusieurs constructeurs admettent en coulisses que l\u2019<strong>\u00e9lectrique<\/strong> n\u2019est pas compatible avec la philosophie des sportives : trop lourdes, trop silencieuses, trop lisses.<\/p>\n<figure id=\"attachment_13000\" aria-describedby=\"caption-attachment-13000\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13000\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1440\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-scaled.jpg 2560w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-300x169.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-1024x576.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-768x432.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-1536x864.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-2048x1152.jpg 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-696x392.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-1068x601.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-1920x1080.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/mercedes-eqs-600x338.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-13000\" class=\"wp-caption-text\">Mercedes-Benz EQS, Modelljahr 2024 \u00a9 DR<\/figcaption><\/figure>\n<p><strong>Maserati<\/strong> avait d\u00e9j\u00e0 abandonn\u00e9 l\u2019an dernier son projet d\u2019hypercar enti\u00e8rement \u00e9lectrique. <a href=\"https:\/\/www.forbes.be\/fr\/elettrica-la-premiere-ferrari-100-electrique-est-annoncee\/\" target=\"_blank\" rel=\"noopener\"><strong>Ferrar<\/strong>i reporte <em>sine die<\/em> son second mod\u00e8le \u00e9lectrique<\/a>, la demande pour des EV de luxe \u00e9tant jug\u00e9e insuffisante. <strong>Porsche<\/strong>, pourtant pionnier avec la <strong>Taycan<\/strong>, se reconcentre sur des <strong>mod\u00e8les thermiques<\/strong> et <strong>hybrides rechargeables<\/strong>. <strong>Mercedes<\/strong> \u00e9prouve des difficult\u00e9s \u00e0 \u00e9couler son EQS.<\/p>\n<h2>Une fracture entre vision politique et r\u00e9alit\u00e9 industrielle<\/h2>\n<p>Le d\u00e9bat r\u00e9v\u00e8le une tension grandissante entre deux temporalit\u00e9s : celle des politiques climatiques et celle des march\u00e9s.<\/p>\n<p>Pour les ONG comme <a href=\"https:\/\/www.transportenvironment.org\/\" target=\"_blank\" rel=\"noopener\">Transport &amp; Environment<\/a>, revenir sur les objectifs europ\u00e9ens reviendrait \u00e0 \u00ab <em>se tirer une balle dans le pied<\/em> \u00bb. \u00ab <em>Affaiblir les objectifs europ\u00e9ens sur les <strong>constructeurs automobiles<\/strong> et ralentir l\u2019<strong>\u00e9lectrification<\/strong>, c\u2019est d\u00e9manteler les efforts qui sont faits<\/em> \u00bb, estime <strong>Lucien Mathieu<\/strong>, directeur \u00ab\u00a0voitures\u00a0\u00bb de l\u2019organisation.<br \/>\nMais pour les constructeurs, l\u2019urgence est ailleurs : ajuster la trajectoire avant la casse.<\/p>\n<p>Car une transition mal calibr\u00e9e pourrait aboutir \u00e0 l\u2019effet inverse, \u00e0 savoir moins de ventes, des usines sous-utilis\u00e9es et un ralentissement des investissements. \u00ab <em>Ce n\u2019est pas un retour en arri\u00e8re que nous demandons, mais une adaptation du rythme pour coller \u00e0 la r\u00e9alit\u00e9. Nous ne changeons pas notre strat\u00e9gie<\/em> \u00bb, insiste en effet <strong>Xavier Martinet<\/strong> (Hyundai Motor Europe).<\/p>\n<h2>Calendrier revu<\/h2>\n<p>La voiture \u00e9lectrique n\u2019est pas morte, loin de l\u00e0. Mais l\u2019euphorie initiale c\u00e8de la place \u00e0 un r\u00e9alisme industriel. Les prochains mois seront d\u00e9cisifs : entre pressions politiques, contraintes \u00e9conomiques et exigences \u00e9cologiques, l\u2019Europe cherche un nouveau point d\u2019\u00e9quilibre.<\/p>\n<figure id=\"attachment_13003\" aria-describedby=\"caption-attachment-13003\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13003\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1621\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-scaled.jpg 2560w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-300x190.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-1024x648.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-768x486.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-1536x973.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-2048x1297.jpg 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-696x441.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-1068x676.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-1920x1216.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/shutterstock-2673584081-600x380.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-13003\" class=\"wp-caption-text\">\u00a9 DR\/Shutterstock.com<\/figcaption><\/figure>\n<p>Lors d\u2019une rencontre avec les principaux acteurs de l\u2019industrie automobile europ\u00e9enne, la Commission europ\u00e9enne a annonc\u00e9 son intention de r\u00e9examiner \u00ab <em>dans les meilleurs d\u00e9lais<\/em> \u00bb l\u2019interdiction programm\u00e9e pour 2035 de la vente de <strong>v\u00e9hicules thermiques neufs<\/strong> au sein de l\u2019Union. <strong>Ursula von der Leyen<\/strong> a soulign\u00e9 sur Twitter que cet examen viserait \u00e0 \u00ab <em>garantir que l\u2019Europe demeure \u00e0 l\u2019avant-garde de l\u2019innovation automobile<\/em> \u00bb. Cette annonce intervient dans un contexte o\u00f9 les constructeurs avaient d\u00e9j\u00e0 obtenu un assouplissement des normes de CO2, permettant d\u2019\u00e9taler leur mise en \u0153uvre sur trois ann\u00e9es, jusqu\u2019en 2027, refl\u00e9tant ainsi les tensions entre ambitions environnementales et r\u00e9alit\u00e9s industrielles.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">We want the future of cars \u2013 and the cars of the future \u2013 to be made in Europe.<\/p>\n<p>So we are working hand in hand with industry to make this a reality.<\/p>\n<p>Today, we held our third Strategic Dialogue with the automotive sector, and our Industrial Action Plan is already delivering\u2026<\/p>\n<p>\u2014 Ursula von der Leyen (@vonderleyen) <a href=\"https:\/\/twitter.com\/vonderleyen\/status\/1966481758464942316?ref_src=twsrc%5Etfw\">September 12, 2025<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Le <strong>moteur \u00e9lectrique<\/strong>, symbole de modernit\u00e9, ne manque pas de puissance. Mais c\u2019est d\u00e9sormais la volont\u00e9 collective de le faire avancer qui semble devoir \u00eatre recharg\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Longtemps per\u00e7ue comme une r\u00e9volution in\u00e9vitable, la voiture \u00e9lectrique semble aujourd\u2019hui traverser une zone de turbulences. Les constructeurs (europ\u00e9ens) plaident pour un ralentissement du calendrier europ\u00e9en, accusant une demande trop timide et un cadre r\u00e9glementaire d\u00e9connect\u00e9 du terrain. La transition, promise comme lin\u00e9aire et rapide, s\u2019av\u00e8re plus fragile qu\u2019esp\u00e9r\u00e9. Pendant des ann\u00e9es, les salons automobiles [&hellip;]<\/p>\n","protected":false},"author":54,"featured_media":13002,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[74,49,14,77],"tags":[],"class_list":["post-12702","post","type-post","status-publish","format-standard","has-post-thumbnail","category-automobile","category-environnement","category-innovation","category-international"],"acf":[],"_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"Face \u00e0 une demande en baisse et \u00e0 des co\u00fbts \u00e9lev\u00e9s, l\u2019Europe revoit le calendrier de la fin du thermique : la voiture \u00e9lectrique entre dans une phase de doute.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9 | Forbes Belgique<\/title>\n<meta name=\"description\" content=\"Face \u00e0 une demande en baisse et \u00e0 des co\u00fbts \u00e9lev\u00e9s, l\u2019Europe revoit le calendrier de la fin du thermique : la voiture \u00e9lectrique entre dans une phase de doute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9 | Forbes Belgique\" \/>\n<meta property=\"og:description\" content=\"Face \u00e0 une demande en baisse et \u00e0 des co\u00fbts \u00e9lev\u00e9s, l\u2019Europe revoit le calendrier de la fin du thermique : la voiture \u00e9lectrique entre dans une phase de doute.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-23T05:35:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2025-10-21-a-143910-e1761117132589.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2040\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Igor Lihaut\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Igor Lihaut\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/\"},\"author\":{\"name\":\"Igor Lihaut\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/c3092240d98bc6606f1342fb37d786a1\"},\"headline\":\"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9\",\"datePublished\":\"2025-10-23T05:35:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/\"},\"wordCount\":1057,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/capture-decran-2025-10-21-a-143910-e1761117132589.png\",\"articleSection\":[\"Automobile\",\"Environnement\",\"Innovation\",\"International\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/\",\"name\":\"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9 | Forbes Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/capture-decran-2025-10-21-a-143910-e1761117132589.png\",\"datePublished\":\"2025-10-23T05:35:56+00:00\",\"description\":\"Face \u00e0 une demande en baisse et \u00e0 des co\u00fbts \u00e9lev\u00e9s, l\u2019Europe revoit le calendrier de la fin du thermique : la voiture \u00e9lectrique entre dans une phase de doute.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/capture-decran-2025-10-21-a-143910-e1761117132589.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/capture-decran-2025-10-21-a-143910-e1761117132589.png\",\"width\":2040,\"height\":1068,\"caption\":\"\u00a9 Hyundai\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/c3092240d98bc6606f1342fb37d786a1\",\"name\":\"Igor Lihaut\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96ee194e85cfc604c40d77778a57130425bb8cff0d6206dfbb9672e7ad8275de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96ee194e85cfc604c40d77778a57130425bb8cff0d6206dfbb9672e7ad8275de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96ee194e85cfc604c40d77778a57130425bb8cff0d6206dfbb9672e7ad8275de?s=96&d=mm&r=g\",\"caption\":\"Igor Lihaut\"},\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/gregorylivishotmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9 | Forbes Belgique","description":"Face \u00e0 une demande en baisse et \u00e0 des co\u00fbts \u00e9lev\u00e9s, l\u2019Europe revoit le calendrier de la fin du thermique : la voiture \u00e9lectrique entre dans une phase de doute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/","og_locale":"fr_FR","og_type":"article","og_title":"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9 | Forbes Belgique","og_description":"Face \u00e0 une demande en baisse et \u00e0 des co\u00fbts \u00e9lev\u00e9s, l\u2019Europe revoit le calendrier de la fin du thermique : la voiture \u00e9lectrique entre dans une phase de doute.","og_url":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2025-10-23T05:35:56+00:00","og_image":[{"width":2040,"height":1068,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2025-10-21-a-143910-e1761117132589.png","type":"image\/png"}],"author":"Igor Lihaut","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Igor Lihaut","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/"},"author":{"name":"Igor Lihaut","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/c3092240d98bc6606f1342fb37d786a1"},"headline":"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9","datePublished":"2025-10-23T05:35:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/"},"wordCount":1057,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2025-10-21-a-143910-e1761117132589.png","articleSection":["Automobile","Environnement","Innovation","International"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/","url":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/","name":"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9 | Forbes Belgique","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2025-10-21-a-143910-e1761117132589.png","datePublished":"2025-10-23T05:35:56+00:00","description":"Face \u00e0 une demande en baisse et \u00e0 des co\u00fbts \u00e9lev\u00e9s, l\u2019Europe revoit le calendrier de la fin du thermique : la voiture \u00e9lectrique entre dans une phase de doute.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2025-10-21-a-143910-e1761117132589.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/10\/capture-decran-2025-10-21-a-143910-e1761117132589.png","width":2040,"height":1068,"caption":"\u00a9 Hyundai"},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/la-desillusion-electrique-lenthousiasme-des-constructeurs-automobiles-se-heurte-a-la-realite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"La d\u00e9sillusion \u00e9lectrique : l\u2019enthousiasme des constructeurs automobiles se heurte \u00e0 la r\u00e9alit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/c3092240d98bc6606f1342fb37d786a1","name":"Igor Lihaut","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/96ee194e85cfc604c40d77778a57130425bb8cff0d6206dfbb9672e7ad8275de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96ee194e85cfc604c40d77778a57130425bb8cff0d6206dfbb9672e7ad8275de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96ee194e85cfc604c40d77778a57130425bb8cff0d6206dfbb9672e7ad8275de?s=96&d=mm&r=g","caption":"Igor Lihaut"},"url":"https:\/\/www.forbes.be\/fr\/author\/gregorylivishotmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/12702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=12702"}],"version-history":[{"count":4,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/12702\/revisions"}],"predecessor-version":[{"id":13030,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/12702\/revisions\/13030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/13002"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=12702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=12702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=12702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}