{"id":15645,"date":"2026-04-14T21:48:39","date_gmt":"2026-04-14T19:48:39","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=15645"},"modified":"2026-04-14T21:48:39","modified_gmt":"2026-04-14T19:48:39","slug":"rein-meirte-clusity-revolution-tech","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/","title":{"rendered":"Rein Meirte, 30 Under 30 : \u00ab au moins 50% des recrutements se d\u00e9roulent par r\u00e9seautage \u00bb"},"content":{"rendered":"<p><b>Le 28 novembre 2025, Rein Meirte a \u00e9t\u00e9 s\u00e9lectionn\u00e9e avec 29 autres jeunes pour la seconde liste belge des 30 Under 30. Aujourd&rsquo;hui, Rein revient sur son parcours pour Forbes et parle de ce que l&rsquo;avenir r\u00e9serve.<\/b><\/p>\n<p>Rein Meirte est la fondatrice de <a href=\"https:\/\/www.clusity.be\/\">Clusity<\/a>, la plus grande communaut\u00e9 pour les femmes dans le secteur technologique en Belgique, et partenaire fondatrice du <a href=\"https:\/\/www.femfutures.com\/\">FemFutures Collective<\/a>, o\u00f9 elle \u0153uvre pour l&rsquo;entrepreneuriat en femtech. Dans une optique o\u00f9 notre vie quotidienne et notre avenir sont dict\u00e9s par la technologie, elle estime que celle-ci doit \u00eatre d\u00e9velopp\u00e9e par tout le monde. Chez Clusity, elle vise \u00e0 rendre le travail en technologie plus accessible, en connectant femmes, alli\u00e9s et entreprises gr\u00e2ce \u00e0 des \u00e9v\u00e9nements, du mentorat et des recherches.<\/p>\n<p><b>Forbes.be &#8211; \u00e9tait-ce \u00e9vident pour vous d\u00e8s le d\u00e9part de vous lancer dans la technologie ?<\/b><br \/>\nRein Meirte &#8211; Pas du tout. Adolescente, je n&rsquo;aimais pas \u00eatre sur les bancs de l&rsquo;\u00e9cole. J&rsquo;ai compl\u00e9t\u00e9 ma derni\u00e8re ann\u00e9e du secondaire en quatre mois via la commission d&rsquo;examen. Cela m&rsquo;a fait r\u00e9aliser que j&rsquo;avais des capacit\u00e9s, mais que je ne m&rsquo;adaptais pas au syst\u00e8me scolaire &#8211; et cela a confirm\u00e9 mon d\u00e9sir d&rsquo;autonomie. \u00c0 17 ans, je suis partie \u00e0 l&rsquo;\u00e9tranger pendant un an car je ne savais pas encore quoi \u00e9tudier. En Bolivie, j&rsquo;ai donn\u00e9 des cours de violon et d&rsquo;anglais dans le cadre d&rsquo;un projet de musique sociale. Ensuite, j&rsquo;ai \u00e9tudi\u00e9 pendant six mois \u00e0 Cuba au conservatoire. C&rsquo;est pr\u00e9cis\u00e9ment en m&rsquo;immergeant dans la musique que j&rsquo;ai d\u00e9couvert que le style de vie classique des musiciens &#8211; avec peu d&rsquo;autonomie &#8211; ne me convenait pas. De retour en Belgique, j&rsquo;ai explor\u00e9 toutes sortes de formations, de la photographie \u00e0 l&rsquo;ing\u00e9nierie commerciale. Finalement, j&rsquo;ai choisi le Management de l&rsquo;Innovation \u00e0 Bruxelles, car c&rsquo;\u00e9tait \u00e0 la fois large et ax\u00e9 sur l&rsquo;avenir : technologie, entrepreneuriat, impact. Cela correspondait \u00e0 ce que j&rsquo;avais ressenti en Am\u00e9rique du Sud : je voulais faire un travail qui avait du sens. Je viens aussi d&rsquo;une famille o\u00f9 la technologie a toujours \u00e9t\u00e9 pr\u00e9sente : mes fr\u00e8res travaillent dans la tech, mon p\u00e8re est biologiste mais programmeur dans l&rsquo;\u00e2me. Pour moi, la technologie n&rsquo;a jamais \u00e9t\u00e9 une fin en soi, mais un levier pour avoir un impact. Ce fil rouge &#8211; autonomie, impact et technologie comme moyen &#8211; traverse tout mon parcours jusqu&rsquo;\u00e0 Clusity. Apr\u00e8s mes \u00e9tudes, j&rsquo;ai int\u00e9gr\u00e9 le monde de l&rsquo;IT, au sein d&rsquo;un groupe d&rsquo;entreprises technologiques sous De Cronos Groep. J&rsquo;y ai travaill\u00e9 comme marketeur digital et de l&rsquo;innovation. C&rsquo;est l\u00e0 que j&rsquo;ai rencontr\u00e9 ma cofondatrice Elke Kraemer &#8211; nous sommes tr\u00e8s diff\u00e9rentes, mais tr\u00e8s compl\u00e9mentaires.<\/p>\n<p><b>&#8211; Comment est n\u00e9e l&rsquo;id\u00e9e de Clusity ?<\/b><br \/>\n&#8211; Dans ce premier emploi, nous avons constat\u00e9 de pr\u00e8s \u00e0 quel point le secteur technologique est toujours homog\u00e8ne. La technologie d\u00e9termine comment nous travaillons, vivons et interagissons. Si cette technologie est presque exclusivement con\u00e7ue par un seul groupe &#8211; principalement des hommes blancs pour le moment &#8211; elle est forc\u00e9ment pens\u00e9e \u00e0 travers un prisme unique. Elke \u00e9tait \u00e0 un tournant de sa carri\u00e8re &#8211; elle approchait de la cinquantaine &#8211; et se demandait : \u00ab Est-ce tout ou vais-je r\u00e9aliser mon r\u00eave entrepreneurial ? \u00bb J&rsquo;avais faim d&rsquo;entrepreneuriat et d&rsquo;impact social. Nous avons alors approch\u00e9 l&rsquo;un des fondateurs de De Cronos Groep avec essentiellement une mission et pas encore de mod\u00e8le d&rsquo;affaires. Il croyait en le probl\u00e8me et en nous, et nous a offert l&rsquo;espace et les ressources pour l&rsquo;explorer \u00e0 fond. Cela a vraiment acc\u00e9l\u00e9r\u00e9 notre lancement, et nous lui en sommes encore immens\u00e9ment reconnaissantes.<\/p>\n<p><b>&#8211; Qu&rsquo;avez-vous exactement d\u00e9couvert lors de cette recherche exploratoire ?<\/b><br \/>\n&#8211; Deux \u00e9l\u00e9ments se sont distingu\u00e9s. Premi\u00e8rement, votre r\u00e9seau d\u00e9termine \u00e9norm\u00e9ment de choses. Des recherches sur les pratiques de recrutement montrent que les r\u00e9seaux jouent un r\u00f4le crucial dans la recherche d&#8217;emploi, ce qui signifie que l&rsquo;acc\u00e8s aux opportunit\u00e9s est fortement influenc\u00e9 par qui vous connaissez.Deuxi\u00e8mement, le biais de similarit\u00e9. Les gens ont tendance \u00e0 s&rsquo;entourer de personnes qui leur ressemblent en termes de genre, de couleur de peau, d&rsquo;\u00e2ge, et m\u00eame de taille. Les femmes dans la tech connaissaient en moyenne beaucoup d&rsquo;autres femmes dans le secteur, mais ces r\u00e9seaux \u00e9taient fragment\u00e9s. C&rsquo;est l\u00e0 qu&rsquo;il y a un levier \u00e9norme. Dans un secteur principalement masculin, cela signifie : des hommes avec des r\u00e9seaux pleins d&rsquo;hommes, et donc plus de la m\u00eame chose.<\/p>\n<p><b>&#8211; Comment cela se traduit-il aujourd&rsquo;hui dans ce que fait Clusity ?<\/b><br \/>\n&#8211; Nous avons deux volets : la communaut\u00e9 et les organisations. Du c\u00f4t\u00e9 de la communaut\u00e9, nous avons d\u00e9j\u00e0 rassembl\u00e9 plus de 4 000 femmes dans la tech, en Belgique et au-del\u00e0. Nous organisons des \u00e9v\u00e9nements mensuels sur des sujets tech concrets, avons un programme de mentorat, un programme d&rsquo;ambassadeurs, des parcours de prise de parole en public, et un programme pour chercheuses d&#8217;emploi. Tout tourne autour de trois axes : r\u00e9seau, r\u00f4les mod\u00e8les et soutien. Du c\u00f4t\u00e9 des organisations, nous avons d\u00e9j\u00e0 collabor\u00e9 avec plus de 40 entreprises. D&rsquo;une part, nous les aidons \u00e0 attirer plus de talents f\u00e9minins &#8211; via le branding employeur, des \u00e9v\u00e9nements, le matching de talents. D&rsquo;autre part, nous les accompagnons en interne sur la diversit\u00e9 et l&rsquo;inclusion : ateliers, conf\u00e9rences, parcours pour rendre la culture, les politiques et le leadership plus inclusifs.<\/p>\n<p><b>&#8211; Comment concr\u00e9tisez-vous cela pour les entreprises qui souhaitent, par exemple, \u00ab\u00a0plus de femmes\u00a0\u00bb, mais ne savent pas comment s&rsquo;y prendre ?<\/b><br \/>\n&#8211; Tout commence par mesurer honn\u00eatement : combien de femmes avez-vous actuellement, dans quelles fonctions, quels sont les flux d&rsquo;entr\u00e9es, qui progresse, qui abandonne ? De nombreuses entreprises surestiment leurs chiffres.Ensuite, nous examinons : o\u00f9 trouvez-vous les femmes que vous recherchez, comment les abordez-vous, et comment vous assurez-vous qu&rsquo;elles ne viennent pas seulement, mais restent aussi ? Cela concerne les descriptions de poste, le branding employeur, les canaux de recrutement, mais aussi la culture, les r\u00f4les mod\u00e8les, le style de leadership et les opportunit\u00e9s de progression.<\/p>\n<p><b>&#8211; O\u00f9 souhaitez-vous voir Clusity dans cinq ans ?<\/b><br \/>\n&#8211; Nous voulons atteindre une bien plus grande partie des femmes dans la tech en Belgique et les aider \u00e0 progresser vers des postes de direction. Les femmes en management et aux postes de PDG restent encore cruellement sous-repr\u00e9sent\u00e9es. En outre, nous voulons renforcer notre r\u00f4le de passerelle entre le talent et les entreprises, et collaborer encore plus \u00e9troitement avec l&rsquo;\u00e9ducation, les organisations \u00e0 but non lucratif et les projets de l&rsquo;UE. La technologie ne s&rsquo;arr\u00eate pas aux fronti\u00e8res, l&rsquo;inclusion non plus.<\/p>\n<p><b>&#8211; Pour finir, quel conseil donneriez-vous aux autres jeunes entrepreneurs ?<\/b><br \/>\n&#8211; L&rsquo;entrepreneuriat n&rsquo;est pas un acte solitaire. Trouvez vos alli\u00e9s. Sans ma cofondatrice Elke, sans notre premier investisseur, sans mes mentors, je ne serais pas l\u00e0. Il y a eu des moments o\u00f9 je me suis demand\u00e9 : \u00ab\u00a0Pourquoi fais-je cela ? Je vais ouvrir un caf\u00e9 et mener une vie tranquille.\u00a0\u00bb \u00c0 ces moments, il vous faut des gens qui vous aident \u00e0 vous r\u00e9orienter : revenir vers ce qui vous donne de l&rsquo;\u00e9nergie, vers comment ajuster le tir plut\u00f4t que d&rsquo;abandonner. Et ne vous laissez pas perturber par les \u00e2ges et les listes. J&rsquo;ai commenc\u00e9 jeune parce que ma trajectoire a pris ce chemin, mais ce n&rsquo;est pas une norme. L&rsquo;impact n&rsquo;a pas de date d&rsquo;expiration. L&rsquo;essentiel est : souhaitez-vous apporter une contribution positive, et \u00eates-vous pr\u00eat \u00e0 y travailler de mani\u00e8re coh\u00e9rente ? Le reste, c&rsquo;est du bruit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 28 novembre 2025, Rein Meirte a \u00e9t\u00e9 s\u00e9lectionn\u00e9e avec 29 autres jeunes pour la seconde liste belge des 30 Under 30. Aujourd&rsquo;hui, Rein revient sur son parcours pour Forbes et parle de ce que l&rsquo;avenir r\u00e9serve. Rein Meirte est la fondatrice de Clusity, la plus grande communaut\u00e9 pour les femmes dans le secteur technologique en Belgique, et partenaire fondatrice du [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":15644,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[19,22,59],"tags":[],"class_list":["post-15645","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entrepreneurs","category-femmes-forbes","category-forbes-30-30"],"acf":[],"_yoast_wpseo_title":"Rein Meirte : Clusity et l'impact des femmes en tech","_yoast_wpseo_metadesc":"D\u00e9couvrez comment Rein Meirte r\u00e9volutionne la place des femmes dans la tech avec Clusity et ses perspectives pour l'avenir.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rein Meirte : Clusity et l&#039;impact des femmes en tech<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment Rein Meirte r\u00e9volutionne la place des femmes dans la tech avec Clusity et ses perspectives pour l&#039;avenir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rein Meirte : Clusity et l&#039;impact des femmes en tech\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment Rein Meirte r\u00e9volutionne la place des femmes dans la tech avec Clusity et ses perspectives pour l&#039;avenir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T19:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2026\/02\/13784-rein-meirte-2-e1776196074485.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00e9line Bouckaert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00e9line Bouckaert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/\"},\"author\":{\"name\":\"C\u00e9line Bouckaert\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/8ec2eaf66f85ad162d094b61be753342\"},\"headline\":\"Rein Meirte, 30 Under 30 : \u00ab au moins 50% des recrutements se d\u00e9roulent par r\u00e9seautage \u00bb\",\"datePublished\":\"2026-04-14T19:48:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/\"},\"wordCount\":1285,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13784-rein-meirte-2-e1776196074485.jpg\",\"articleSection\":[\"Entrepreneurs\",\"Femmes Forbes\",\"Forbes 30-30\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/\",\"name\":\"Rein Meirte : Clusity et l'impact des femmes en tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13784-rein-meirte-2-e1776196074485.jpg\",\"datePublished\":\"2026-04-14T19:48:39+00:00\",\"description\":\"D\u00e9couvrez comment Rein Meirte r\u00e9volutionne la place des femmes dans la tech avec Clusity et ses perspectives pour l'avenir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13784-rein-meirte-2-e1776196074485.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/13784-rein-meirte-2-e1776196074485.jpg\",\"width\":1150,\"height\":603,\"caption\":\"Rein Meirte \u00a9 AS Agency\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/rein-meirte-clusity-revolution-tech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rein Meirte, 30 Under 30 : \u00ab au moins 50% des recrutements se d\u00e9roulent par r\u00e9seautage \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/8ec2eaf66f85ad162d094b61be753342\",\"name\":\"C\u00e9line Bouckaert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/0283_ec_fb-1-150x150.jpg\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/0283_ec_fb-1-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/0283_ec_fb-1-150x150.jpg\",\"caption\":\"C\u00e9line Bouckaert\"},\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/cboeditionventures-be\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rein Meirte : Clusity et l'impact des femmes en tech","description":"D\u00e9couvrez comment Rein Meirte r\u00e9volutionne la place des femmes dans la tech avec Clusity et ses perspectives pour l'avenir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/","og_locale":"fr_FR","og_type":"article","og_title":"Rein Meirte : Clusity et l'impact des femmes en tech","og_description":"D\u00e9couvrez comment Rein Meirte r\u00e9volutionne la place des femmes dans la tech avec Clusity et ses perspectives pour l'avenir.","og_url":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2026-04-14T19:48:39+00:00","og_image":[{"width":1150,"height":603,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2026\/02\/13784-rein-meirte-2-e1776196074485.jpg","type":"image\/jpeg"}],"author":"C\u00e9line Bouckaert","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"C\u00e9line Bouckaert","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/"},"author":{"name":"C\u00e9line Bouckaert","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/8ec2eaf66f85ad162d094b61be753342"},"headline":"Rein Meirte, 30 Under 30 : \u00ab au moins 50% des recrutements se d\u00e9roulent par r\u00e9seautage \u00bb","datePublished":"2026-04-14T19:48:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/"},"wordCount":1285,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2026\/02\/13784-rein-meirte-2-e1776196074485.jpg","articleSection":["Entrepreneurs","Femmes Forbes","Forbes 30-30"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/","url":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/","name":"Rein Meirte : Clusity et l'impact des femmes en tech","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2026\/02\/13784-rein-meirte-2-e1776196074485.jpg","datePublished":"2026-04-14T19:48:39+00:00","description":"D\u00e9couvrez comment Rein Meirte r\u00e9volutionne la place des femmes dans la tech avec Clusity et ses perspectives pour l'avenir.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2026\/02\/13784-rein-meirte-2-e1776196074485.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2026\/02\/13784-rein-meirte-2-e1776196074485.jpg","width":1150,"height":603,"caption":"Rein Meirte \u00a9 AS Agency"},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/rein-meirte-clusity-revolution-tech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Rein Meirte, 30 Under 30 : \u00ab au moins 50% des recrutements se d\u00e9roulent par r\u00e9seautage \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/8ec2eaf66f85ad162d094b61be753342","name":"C\u00e9line Bouckaert","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/0283_ec_fb-1-150x150.jpg","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/0283_ec_fb-1-150x150.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/0283_ec_fb-1-150x150.jpg","caption":"C\u00e9line Bouckaert"},"url":"https:\/\/www.forbes.be\/fr\/author\/cboeditionventures-be\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/15645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=15645"}],"version-history":[{"count":3,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/15645\/revisions"}],"predecessor-version":[{"id":16725,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/15645\/revisions\/16725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/15644"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=15645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=15645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=15645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}