{"id":3353,"date":"2024-07-11T10:20:38","date_gmt":"2024-07-11T08:20:38","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=3353"},"modified":"2026-02-24T18:58:35","modified_gmt":"2026-02-24T17:58:35","slug":"la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/","title":{"rendered":"La nouvelle Volvo EX30, un SUV \u00e9lectrique aux grandes performances"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, <a href=\"https:\/\/www.volvocars.com\/fr-be\/cars\/ex30-electric\/\" target=\"_blank\" rel=\"noopener\">la Volvo EX30<\/a>. Ce v\u00e9hicule int\u00e8gre des innovations techniques significatives tant sur le plan de la conception que de la production, offrant une r\u00e9ponse moderne aux besoins de mobilit\u00e9 actuels.<\/span><\/p>\n<h2>R\u00e9compens\u00e9 pour son design<\/h2>\n<p><span style=\"font-weight: 400;\">Le mod\u00e8le a \u00e9t\u00e9 r\u00e9compens\u00e9 par le prestigieux Red Dot \u00ab\u00a0Best of the Best\u00a0\u00bb Design Award, une distinction qui souligne le soin apport\u00e9 au design. La EX30 se distingue par son empattement long, ses grandes roues et ses d\u00e9battements \u00e9gaux, conf\u00e9rant \u00e0 son ext\u00e9rieur un \u00e9quilibre et un raffinement sans pareil. L&rsquo;int\u00e9rieur de la voiture marque une avanc\u00e9e significative vers les objectifs de durabilit\u00e9 de Volvo gr\u00e2ce \u00e0 l&rsquo;utilisation de mat\u00e9riaux naturels et recycl\u00e9s. De plus, l&rsquo;espace disponible a \u00e9t\u00e9 optimis\u00e9, avec un design int\u00e9rieur centralis\u00e9 int\u00e9grant le stockage, les commandes et les \u00e9crans de mani\u00e8re harmonieuse, cr\u00e9ant ainsi un espace flexible et bien proportionn\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00ab <\/span><i><span style=\"font-weight: 400;\">La<a href=\"https:\/\/www.volvocars.com\/fr-be\/cars\/ex30-electric\/\" target=\"_blank\" rel=\"noopener\"> Volvo EX30<\/a> incarne les valeurs de design de Volvo Cars dans un format plus petit et constitue une vitrine du design scandinave haut de gamme, o\u00f9 la fonction d\u00e9termine la forme<\/span><\/i><span style=\"font-weight: 400;\"> \u00bb, d\u00e9clare Jim Rowan, CEO de Volvo Cars.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9quip\u00e9 d&rsquo;une batterie qui permet de parcourir jusqu&rsquo;\u00e0 476 km, le mod\u00e8le est con\u00e7u pour les longs trajets sans besoin de rechargements fr\u00e9quents. De plus, le v\u00e9hicule peut passer de 10% \u00e0 80% de charge en seulement 26 minutes avec l&rsquo;utilisation d&rsquo;un chargeur rapide, offrant ainsi une grande flexibilit\u00e9 aux conducteurs.<\/span><\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #tdi_1  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item5 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_1  .td-doubleSlider-2 .td-item6 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"tdi_1\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 6<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" title=\"Volvo EX30 Cloud Blue Exterior\"  data-caption=\"Ext\u00e9rieur de la Volvo EX30 Cloud Blue\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg 1708w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-200x300.jpg 200w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-683x1024.jpg 683w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-768x1151.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-1025x1536.jpg 1025w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-1366x2048.jpg 1366w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-696x1043.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-1068x1601.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-1920x2878.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318853_Volvo_EX30_Cloud_Blue_Exterior-600x899.jpg 600w\" sizes=\"(max-width: 1708px) 100vw, 1708px\" alt=\"Ext&eacute;rieur de la Volvo EX30 Cloud Blue\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Ext\u00e9rieur de la Volvo EX30 Cloud Blue<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" title=\"Volvo EX30 Cloud Blue Exterior\"  data-caption=\"Ext\u00e9rieur de la Volvo EX30 Cloud Blue\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg 1708w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-200x300.jpg 200w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-683x1024.jpg 683w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-768x1151.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-1025x1536.jpg 1025w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-1366x2048.jpg 1366w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-696x1043.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-1068x1601.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-1920x2878.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318854_Volvo_EX30_Cloud_Blue_Exterior-600x899.jpg 600w\" sizes=\"(max-width: 1708px) 100vw, 1708px\" alt=\"Ext&eacute;rieur de la Volvo EX30 Cloud Blue\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Ext\u00e9rieur de la Volvo EX30 Cloud Blue<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" title=\"Volvo EX30 Cloud Blue Exterior\"  data-caption=\"Ext\u00e9rieur de la Volvo EX30 Cloud Blue\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg 1708w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-200x300.jpg 200w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-683x1024.jpg 683w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-768x1151.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-1025x1536.jpg 1025w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-1366x2048.jpg 1366w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-696x1043.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-1068x1601.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-1920x2878.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318855_Volvo_EX30_Cloud_Blue_Exterior-600x899.jpg 600w\" sizes=\"(max-width: 1708px) 100vw, 1708px\" alt=\"Ext&eacute;rieur de la Volvo EX30 Cloud Blue\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Ext\u00e9rieur de la Volvo EX30 Cloud Blue<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-scaled.jpg\" title=\"Volvo EX30 Cloud Blue Interior\"  data-caption=\"Int\u00e9rieur de la Volvo EX30 Cloud Blue\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-scaled.jpg 1707w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-200x300.jpg 200w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-683x1024.jpg 683w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-768x1152.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-1024x1536.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-1366x2048.jpg 1366w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-696x1044.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-1068x1602.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-1920x2880.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318818_Volvo_EX30_Cloud_Blue_Interior-600x900.jpg 600w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" alt=\"Volvo EX30 Cloud Blue InteriorInt&eacute;rieur de la Volvo EX30 Cloud Blue\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Int\u00e9rieur de la Volvo EX30 Cloud Blue<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item5\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" title=\"Volvo EX30 Cloud Blue Exterior\"  data-caption=\"Ext\u00e9rieur de la Volvo EX30 Cloud Blue\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg 1708w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-200x300.jpg 200w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-683x1024.jpg 683w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-768x1151.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-1025x1536.jpg 1025w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-1366x2048.jpg 1366w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-696x1043.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-1068x1601.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-1920x2878.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318893_Volvo_EX30_Cloud_Blue_Exterior-600x899.jpg 600w\" sizes=\"(max-width: 1708px) 100vw, 1708px\" alt=\"Ext&eacute;rieur de la Volvo EX30 Cloud Blue\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Ext\u00e9rieur de la Volvo EX30 Cloud Blue<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item6\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" title=\"Volvo EX30 Cloud Blue Exterior\"  data-caption=\"Ext\u00e9rieur de la Volvo EX30 Cloud Blue\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg 1786w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-209x300.jpg 209w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-714x1024.jpg 714w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-768x1101.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-1072x1536.jpg 1072w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-1429x2048.jpg 1429w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-696x998.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-1068x1531.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-1920x2752.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318891_Volvo_EX30_Cloud_Blue_Exterior-600x860.jpg 600w\" sizes=\"(max-width: 1786px) 100vw, 1786px\" alt=\"Ext&eacute;rieur de la Volvo EX30 Cloud Blue\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Ext\u00e9rieur de la Volvo EX30 Cloud Blue<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item5\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item6\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<h2>Empreinte carbone faible<\/h2>\n<p><span style=\"font-weight: 400;\">La EX30 est con\u00e7ue pour \u00eatre le v\u00e9hicule avec l&#8217;empreinte carbone la plus faible de tous les mod\u00e8les Volvo \u00e0 ce jour. \u00ab <\/span><i><span style=\"font-weight: 400;\">La transition vers les v\u00e9hicules \u00e9lectriques est essentielle pour limiter le changement climatique, mais une plus grande transparence sur les d\u00e9fis qu\u2019elle engendre est n\u00e9cessaire pour r\u00e9duire encore davantage les \u00e9missions. En \u00e9tudiant l\u2019empreinte carbone de l\u2019EX30 et en identifiant ses principaux mat\u00e9riaux et processus, nous souhaitons fournir des informations pr\u00e9cieuses qui peuvent aider \u00e0 orienter les d\u00e9cisions de notre entreprise vers un d\u00e9veloppement plus durable, ainsi que celles de l\u2019industrie dans son ensemble<\/span><\/i><span style=\"font-weight: 400;\"> \u00bb , explique Jonas Otterheim, responsable de l\u2019action climatique chez Volvo Cars.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bien entendu, la EX30 offre \u00e9galement le niveau de s\u00e9curit\u00e9 attendu d&rsquo;une\u00a0 Volvo, assurant la protection des occupants et des autres usagers dans les environnements urbains complexes. Ainsi, elle est \u00e9quip\u00e9e de s\u00e9rie d&rsquo;un dispositif de s\u00e9curit\u00e9 sp\u00e9cifique pour les cyclistes qui aide \u00e0 pr\u00e9venir les accidents d&rsquo;\u00a0\u00ab\u00a0ouverture de porte\u00a0\u00bb en avertissant le conducteur lorsqu&rsquo;il s&rsquo;appr\u00eate \u00e0 ouvrir la porte devant un cycliste, un scooter ou un joggeur.<\/span><\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #tdi_2  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_2  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #tdi_2  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-scaled.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"tdi_2\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 3<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" title=\"Volvo EX30 Cloud Blue Exterior\"  data-caption=\"Ext\u00e9rieur de la Volvo EX30 Cloud Blue\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-scaled.jpg 2560w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-300x200.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-1024x683.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-768x512.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-1536x1024.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-2048x1365.jpg 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-696x464.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-1068x712.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-1920x1280.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318894_Volvo_EX30_Cloud_Blue_Exterior-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" alt=\"Ext&eacute;rieur de la Volvo EX30 Cloud Blue\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Ext\u00e9rieur de la Volvo EX30 Cloud Blue<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-scaled.jpg\" title=\"Volvo EX30 Vapour Grey Interior\"  data-caption=\"Int\u00e9rieur de la Volvo EX30 Vapour Grey\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-scaled.jpg 2560w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-300x200.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-1024x683.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-768x512.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-1536x1024.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-2048x1365.jpg 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-696x464.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-1068x712.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-1920x1280.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/318722_Volvo_EX30_Vapour_Grey_Interior-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" alt=\"Int&eacute;rieur de la Volvo EX30 Vapour Grey\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Int\u00e9rieur de la Volvo EX30 Vapour Grey<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-scaled.jpg\" title=\"Volvo EX30 interior\"  data-caption=\"Int\u00e9rieur de la Volvo EX30\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-scaled.jpg\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-scaled.jpg 2560w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-300x278.jpg 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-1024x948.jpg 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-768x711.jpg 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-1536x1421.jpg 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-2048x1895.jpg 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-696x644.jpg 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-1068x988.jpg 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-1920x1777.jpg 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313336_Volvo_EX30_interior-600x555.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" alt=\"Int&eacute;rieur de la Volvo EX30\">\r\n                            <\/a>\r\n                            <figcaption class = \"td-slide-caption td-gallery-slide-content\"><div class = \"td-gallery-slide-copywrite\">Int\u00e9rieur de la Volvo EX30<\/div><\/figcaption>\r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<h2>Jeunes professionnels<\/h2>\n<p><span style=\"font-weight: 400;\">La <a href=\"https:\/\/www.volvocars.com\/fr-be\/cars\/ex30-electric\/\" target=\"_blank\" rel=\"noopener\">Volvo EX30<\/a> est particuli\u00e8rement adapt\u00e9e aux jeunes professionnels en qu\u00eate d\u2019une voiture de soci\u00e9t\u00e9. \u00c9quip\u00e9e d\u2019un syst\u00e8me audio Harman Kardon pour une qualit\u00e9 sonore sup\u00e9rieure et les standards de s\u00e9curit\u00e9 \u00e9lev\u00e9s propres \u00e0 la marque Volvo, la EX30 r\u00e9pond \u00e0 une vari\u00e9t\u00e9 de besoins professionnels et personnels.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Propos\u00e9 \u00e0 un prix de d\u00e9part attractif de 40 590 euros (TVA incluse, en Belgique), le mod\u00e8le fait l\u2019objet d\u2019avantages fiscaux li\u00e9s \u00e0 la conduite \u00e9lectrique.<\/span><\/p>\n<p><em>Cet article \u00e0 \u00e9t\u00e9 r\u00e9dig\u00e9 en \u00e9troite collaboration avec <a href=\"https:\/\/www.volvocars.com\/fr-be\/cars\/ex30-electric\/\" target=\"_blank\" rel=\"noopener\">Volvo<\/a>.<\/em><\/p>\n<p><strong>A lire aussi :<br \/>\n<\/strong><a href=\"https:\/\/www.forbes.be\/fr\/top-des-destinations-plus-belles-opportunites-de-vente-a-lexport-pour-les-pme-belges\/\" target=\"_blank\" rel=\"noopener\">Voici le top des destinations offrant les plus belles opportunit\u00e9s de vente \u00e0 l\u2019export pour les PME belges<\/a><br \/>\n<a href=\"https:\/\/www.forbes.be\/fr\/un-debut-triomphal-pour-la-belgian-golf-league-corporate-a-hulencourt\/\" target=\"_blank\" rel=\"noopener\">Un d\u00e9but triomphal pour la Belgian Golf League Corporate \u00e0 Hulencourt<\/a><br \/>\n<a href=\"https:\/\/www.forbes.be\/fr\/pacte-vert-europeen-bouleversements-politiques-defis-opportunites\/\" target=\"_blank\" rel=\"noopener\">Le Pacte Vert Europ\u00e9en face aux bouleversements politiques<\/a><strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30. Ce v\u00e9hicule int\u00e8gre des innovations techniques significatives tant sur le plan de la conception que de la production, offrant une r\u00e9ponse moderne aux besoins de mobilit\u00e9 actuels. R\u00e9compens\u00e9 pour son design Le mod\u00e8le a \u00e9t\u00e9 r\u00e9compens\u00e9 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[98],"tags":[],"class_list":{"0":"post-3353","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brandvoice"},"acf":[],"_yoast_wpseo_title":"La Volvo EX30, un SUV \u00e9lectrique aux grandes performances","_yoast_wpseo_metadesc":"Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Volvo EX30, un SUV \u00e9lectrique aux grandes performances<\/title>\n<meta name=\"description\" content=\"Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Volvo EX30, un SUV \u00e9lectrique aux grandes performances\" \/>\n<meta property=\"og:description\" content=\"Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T08:20:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-24T17:58:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1339\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BRANDVOICE | Sponsored Content\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"BRANDVOICE | Sponsored Content\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/\"},\"author\":{\"name\":\"BRANDVOICE | Sponsored Content\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/f6bf8fa623babedc7051f16985d6a1d5\"},\"headline\":\"La nouvelle Volvo EX30, un SUV \u00e9lectrique aux grandes performances\",\"datePublished\":\"2024-07-11T08:20:38+00:00\",\"dateModified\":\"2026-02-24T17:58:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/\"},\"wordCount\":631,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg\",\"articleSection\":[\"Brandvoice\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/\",\"name\":\"La Volvo EX30, un SUV \u00e9lectrique aux grandes performances\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg\",\"datePublished\":\"2024-07-11T08:20:38+00:00\",\"dateModified\":\"2026-02-24T17:58:35+00:00\",\"description\":\"Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg\",\"width\":2560,\"height\":1339,\"caption\":\"Ext\u00e9rieur de la Volvo EX30\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nouvelle Volvo EX30, un SUV \u00e9lectrique aux grandes performances\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/f6bf8fa623babedc7051f16985d6a1d5\",\"name\":\"BRANDVOICE | Sponsored Content\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/forbes-thumb-150x150.jpg\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/forbes-thumb-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/forbes-thumb-150x150.jpg\",\"caption\":\"BRANDVOICE | Sponsored Content\"},\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/partenairesforbes-be\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Volvo EX30, un SUV \u00e9lectrique aux grandes performances","description":"Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/","og_locale":"fr_FR","og_type":"article","og_title":"La Volvo EX30, un SUV \u00e9lectrique aux grandes performances","og_description":"Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30.","og_url":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2024-07-11T08:20:38+00:00","article_modified_time":"2026-02-24T17:58:35+00:00","og_image":[{"width":2560,"height":1339,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg","type":"image\/jpeg"}],"author":"BRANDVOICE | Sponsored Content","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"BRANDVOICE | Sponsored Content","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/"},"author":{"name":"BRANDVOICE | Sponsored Content","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/f6bf8fa623babedc7051f16985d6a1d5"},"headline":"La nouvelle Volvo EX30, un SUV \u00e9lectrique aux grandes performances","datePublished":"2024-07-11T08:20:38+00:00","dateModified":"2026-02-24T17:58:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/"},"wordCount":631,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg","articleSection":["Brandvoice"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/","url":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/","name":"La Volvo EX30, un SUV \u00e9lectrique aux grandes performances","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg","datePublished":"2024-07-11T08:20:38+00:00","dateModified":"2026-02-24T17:58:35+00:00","description":"Le secteur automobile continue d\u2019\u00e9voluer rapidement, Volvo en t\u00eate gr\u00e2ce \u00e0 son dernier mod\u00e8le enti\u00e8rement \u00e9lectrique, la Volvo EX30.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2014\/06\/313311_Volvo_EX30_exterior-scaled-e1718271137219.jpg","width":2560,"height":1339,"caption":"Ext\u00e9rieur de la Volvo EX30"},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/la-nouvelle-volvo-ex30-un-suv-electrique-aux-grandes-performances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"La nouvelle Volvo EX30, un SUV \u00e9lectrique aux grandes performances"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/f6bf8fa623babedc7051f16985d6a1d5","name":"BRANDVOICE | Sponsored Content","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/forbes-thumb-150x150.jpg","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/forbes-thumb-150x150.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/forbes-thumb-150x150.jpg","caption":"BRANDVOICE | Sponsored Content"},"url":"https:\/\/www.forbes.be\/fr\/author\/partenairesforbes-be\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/3353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=3353"}],"version-history":[{"count":3,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/3353\/revisions"}],"predecessor-version":[{"id":3367,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/3353\/revisions\/3367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/3355"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=3353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=3353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=3353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}