{"id":8137,"date":"2025-01-15T14:39:20","date_gmt":"2025-01-15T13:39:20","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=8137"},"modified":"2025-01-15T15:39:31","modified_gmt":"2025-01-15T14:39:31","slug":"le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/","title":{"rendered":"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Le g\u00e9ant des services au secteur immobilier professionnel CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious, 3\u00e8me plus grand r\u00e9seau mondial d\u2019espaces de coworking.\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">La soci\u00e9t\u00e9 de coworking <a href=\"https:\/\/www.industriousoffice.com\/fr\/about-us\"><strong>Industrious<\/strong><\/a>, fond\u00e9e aux Etats-Unis en 2012, g\u00e8re aujourd\u2019hui un total de pr\u00e8s de <strong>200 espaces r\u00e9partis dans 65 villes<\/strong> \u00e0 travers le monde. En Belgique, Industrious op\u00e8re un site \u00e0 <a href=\"https:\/\/www.industriousoffice.com\/en\/locations\/kunstlaan-6-9-avenue-des-arts-brussels?igaag=162961904145&amp;igaat=&amp;igacm=21385274375&amp;igacr=716891200223&amp;igakw=industrious&amp;igamt=e&amp;igant=g&amp;locationcode=BE&amp;utm_source=paid_google_brand_europe_be&amp;utm_medium=paid_search&amp;utm_campaign=google-search-brand_europe_be&amp;utm_term=industrious&amp;hsa_acc=7681707284&amp;hsa_cam=21385274375&amp;hsa_grp=162961904145&amp;hsa_ad=716891200223&amp;hsa_src=g&amp;hsa_tgt=kwd-329851781684&amp;hsa_kw=industrious&amp;hsa_mt=e&amp;hsa_net=adwords&amp;hsa_ver=3&amp;gad_source=1&amp;gbraid=0AAAAAC4kPviuI7RP3iuzsQSA4qiRkxTJ2&amp;gclid=EAIaIQobChMI6dHGouj3igMV1gMGAB2tBjC-EAAYASAAEgKE7vD_BwE\"><strong>Bruxelles, avenue des Arts<\/strong><\/a>. Dans le monde, seuls les g\u00e9ants suisse <a href=\"https:\/\/www.iwgplc.com\/en-gb\"><strong>IWG<\/strong><\/a> (groupe propri\u00e9taire des marques Regus ou Spaces, notamment) et am\u00e9ricain <a href=\"https:\/\/fr.wikipedia.org\/wiki\/WeWork\"><strong>WeWork<\/strong><\/a> devancent Industrious par la taille. <a href=\"https:\/\/fr.wikipedia.org\/wiki\/CBRE\"><strong>CBRE<\/strong><\/a> d\u00e9tenait d\u00e9j\u00e0 une participation minoritaire dans Industrious depuis 2020.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8139\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3.webp\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3.webp 1200w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3-300x200.webp 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3-1024x683.webp 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3-768x512.webp 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3-696x464.webp 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3-1068x712.webp 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious3-600x400.webp 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h3 style=\"font-weight: 400;\">Etape strat\u00e9gique pour le secteur du bureau<\/h3>\n<p style=\"font-weight: 400;\">Industrious fera d\u00e9sormais partie d\u2019une des quatre principales divisions de CBRE, \u201cBuilding Operations &amp; Experience\u201d, \u201cExperience\u201d \u00e9tant en grande partie la dimension d&rsquo;accueil et d\u2019hospitalit\u00e9 apport\u00e9e par le mod\u00e8le coworking.<\/p>\n<p style=\"font-weight: 400;\">Cette int\u00e9gration au sein du groupe CBRE marque une \u00e9tape importante dans l\u2019\u00e9volution de l\u2019immobilier de bureau, \u00e0 l\u2019\u00e8re du t\u00e9l\u00e9travail et de la guerre des talents. L\u2019approche coworking am\u00e8ne en effet le monde du bureau classique \u00e0 s\u2019ins\u00e9rer davantage encore dans une pratique r\u00e9solument tourn\u00e9e vers les notions de flexibilit\u00e9, de service personnel et d&rsquo;hospitalit\u00e9.<\/p>\n<p style=\"font-weight: 400;\"><a href=\"https:\/\/www.cbre.com\/people\/bob-sulentic\"><strong>Bob Sulentic, le CEO de CBRE<\/strong><\/a>, justifie le rachat du jour comme un mouvement strat\u00e9gique \u00e0 l\u2019heure o\u00f9 les clients demandent plus d\u2019innovation et moins de rigidit\u00e9 dans les contrats de location classiques. Les espaces de coworking sont con\u00e7us pour \u00eatre conviviaux et pour faciliter l\u2019\u00e9change, un atout pour n\u2019importe quel employeur, aujourd\u2019hui. \u201cDemain, CBRE pourra conseiller une entreprise pour la location d\u2019un espace de bureau sur dix ans et, dans le m\u00eame temps, lui proposer l\u2019acc\u00e8s \u00e0 des espaces de travail coworking dans l\u2019un des sites Industrious\u201d, explique dans un communiqu\u00e9 le patron de CBRE. \u201cCet avantage est capital pour les employeurs \u00e0 l\u2019heure o\u00f9 ces derniers peinent \u00e0 convaincre leurs employ\u00e9s de revenir physiquement au bureau\u201d, poursuit-il.<\/p>\n<p style=\"font-weight: 400;\">La flexibilit\u00e9 offerte par le coworking permet \u00e9galement de g\u00e9rer les risques li\u00e9s \u00e0 la difficult\u00e9 d&rsquo;anticiper les pics d\u2019activit\u00e9. Dans le cas de grands projets, par exemple, les \u00e9quipes sont parfois amen\u00e9es \u00e0 s\u2019\u00e9toffer brusquement, en raison de la participation des ressources externes, pour revenir ensuite \u00e0 des tailles plus r\u00e9duites.<\/p>\n<h3 style=\"font-weight: 400;\">Poursuite de la cr\u00e9dibilisation du secteur du coworking<\/h3>\n<p style=\"font-weight: 400;\">\u201cLe rachat complet de Industrious par CBRE est consid\u00e9r\u00e9 comme un \u00e9v\u00e9nement majeur pour le coworking: il permet de cr\u00e9dibiliser encore un peu plus le secteur comme un mod\u00e8le structurant dans le march\u00e9 du bureau et des lieux de travail\u201d, commente <strong>Jean-Yves Huwart, fondateur de <a href=\"https:\/\/coworkingeurope.net\">Coworking Europe<\/a><\/strong>, r\u00e9seau qui structure et promeut l\u2019industrie du coworking en Europe. \u201cLes environnements coworking sont encore trop per\u00e7us comme r\u00e9serv\u00e9s aux groupes de travailleurs ind\u00e9pendants et au monde des <em>startups<\/em>. En r\u00e9alit\u00e9, le mod\u00e8le aujourd&rsquo;hui mature devient un standard dans l\u2019\u00e9conomie de l\u2019immobilier professionnel. Pas pour remplacer int\u00e9gralement les baux de location classiques mais en compl\u00e9ments indispensables de ceux-ci.\u201d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8140\" src=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656.png\" alt=\"\" width=\"2282\" height=\"1282\" srcset=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656.png 2282w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-300x169.png 300w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-1024x575.png 1024w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-768x431.png 768w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-1536x863.png 1536w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-2048x1151.png 2048w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-696x391.png 696w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-1068x600.png 1068w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-1920x1079.png 1920w, https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/capture-decran-2025-01-15-a-142656-600x337.png 600w\" sizes=\"auto, (max-width: 2282px) 100vw, 2282px\" \/><\/p>\n<p style=\"font-weight: 400;\">La tendance se confirme chaque jour en Belgique, en Europe et ailleurs sur la plan\u00e8te.\u00a0\u201cLes grands op\u00e9rateurs du monde coworking signent aujourd\u2019hui des contrats pour des capacit\u00e9s de centaines de postes de travail\u201d, souligne Jean-Yves Huwart.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le g\u00e9ant des services au secteur immobilier professionnel CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious, 3\u00e8me plus grand r\u00e9seau mondial d\u2019espaces de coworking.\u00a0 La soci\u00e9t\u00e9 de coworking Industrious, fond\u00e9e aux Etats-Unis en 2012, g\u00e8re aujourd\u2019hui un total de pr\u00e8s de 200 espaces r\u00e9partis [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":8138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1,19,24,27],"tags":[],"class_list":["post-8137","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualite","category-entrepreneurs","category-immobilier","category-societe"],"acf":[],"_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"Le g\u00e9ant immobilier CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking | Forbes Belgique<\/title>\n<meta name=\"description\" content=\"Le g\u00e9ant immobilier CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking | Forbes Belgique\" \/>\n<meta property=\"og:description\" content=\"Le g\u00e9ant immobilier CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-15T13:39:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T14:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Philippe Coul\u00e9e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philippe Coul\u00e9e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/\"},\"author\":{\"name\":\"Philippe Coul\u00e9e\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/22bfc3335e560f4084ef5af17ecdad87\"},\"headline\":\"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking\",\"datePublished\":\"2025-01-15T13:39:20+00:00\",\"dateModified\":\"2025-01-15T14:39:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/\"},\"wordCount\":598,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/industrious4.webp\",\"articleSection\":[\"Actualit\u00e9s\",\"Entrepreneurs\",\"Immobilier\",\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/\",\"name\":\"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking | Forbes Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/industrious4.webp\",\"datePublished\":\"2025-01-15T13:39:20+00:00\",\"dateModified\":\"2025-01-15T14:39:31+00:00\",\"description\":\"Le g\u00e9ant immobilier CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/industrious4.webp\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/industrious4.webp\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/22bfc3335e560f4084ef5af17ecdad87\",\"name\":\"Philippe Coul\u00e9e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/unnamed-150x150.jpg\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/unnamed-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/unnamed-150x150.jpg\",\"caption\":\"Philippe Coul\u00e9e\"},\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/philippe-couleeicloud-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking | Forbes Belgique","description":"Le g\u00e9ant immobilier CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/","og_locale":"fr_FR","og_type":"article","og_title":"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking | Forbes Belgique","og_description":"Le g\u00e9ant immobilier CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious.","og_url":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2025-01-15T13:39:20+00:00","article_modified_time":"2025-01-15T14:39:31+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious4.webp","type":"image\/webp"}],"author":"Philippe Coul\u00e9e","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Philippe Coul\u00e9e","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/"},"author":{"name":"Philippe Coul\u00e9e","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/22bfc3335e560f4084ef5af17ecdad87"},"headline":"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking","datePublished":"2025-01-15T13:39:20+00:00","dateModified":"2025-01-15T14:39:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/"},"wordCount":598,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious4.webp","articleSection":["Actualit\u00e9s","Entrepreneurs","Immobilier","Soci\u00e9t\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/","url":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/","name":"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking | Forbes Belgique","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious4.webp","datePublished":"2025-01-15T13:39:20+00:00","dateModified":"2025-01-15T14:39:31+00:00","description":"Le g\u00e9ant immobilier CBRE vient de racheter pour un montant \u00e9valu\u00e9 \u00e0 800 millions de dollars US l\u2019int\u00e9gralit\u00e9 des parts de Industrious.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious4.webp","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2025\/01\/industrious4.webp","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/le-geant-de-limmobilier-cbre-rachete-le-3e-plus-grand-reseau-mondial-de-coworking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Le g\u00e9ant de l\u2019immobilier CBRE rach\u00e8te le 3e plus grand r\u00e9seau mondial de coworking"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/22bfc3335e560f4084ef5af17ecdad87","name":"Philippe Coul\u00e9e","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/unnamed-150x150.jpg","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/unnamed-150x150.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/unnamed-150x150.jpg","caption":"Philippe Coul\u00e9e"},"url":"https:\/\/www.forbes.be\/fr\/author\/philippe-couleeicloud-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/8137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=8137"}],"version-history":[{"count":2,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/8137\/revisions"}],"predecessor-version":[{"id":8143,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/8137\/revisions\/8143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/8138"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=8137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=8137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=8137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}