{"id":966,"date":"2024-07-12T07:00:34","date_gmt":"2024-07-12T05:00:34","guid":{"rendered":"https:\/\/www.forbes.be\/fr\/?p=966"},"modified":"2024-07-17T10:25:13","modified_gmt":"2024-07-17T08:25:13","slug":"7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace","status":"publish","type":"post","link":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/","title":{"rendered":"7 le\u00e7ons d&rsquo;affaires non conventionnelles d&rsquo;un milliardaire du th\u00e9 glac\u00e9"},"content":{"rendered":"<p><strong>Don Vultaggio, patron d&rsquo;Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu&rsquo;il n&rsquo;avait qu&rsquo;un dipl\u00f4me de fin d&rsquo;\u00e9tudes secondaires. Voici sept conseils tir\u00e9s de son ascension entrepreneuriale.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Au milieu des ann\u00e9es 1960, des d\u00e9cennies avant de cr\u00e9er l&rsquo;entreprise qui allait exploser pour devenir l&#8217;empire du th\u00e9 glac\u00e9 <a href=\"https:\/\/drinkarizona.com\/\">Arizona Beverages<\/a>, dont le chiffre d&rsquo;affaires est estim\u00e9 \u00e0 2 milliards de dollars, Don Vultaggio \u00e9tait un adolescent sans histoire qui travaillait pour 1 dollar de l&rsquo;heure dans une \u00e9picerie de Brooklyn et qui r\u00eavait de grandeur. F\u00e9rocement ambitieux, il bricole un pistolet \u00e0 prix avec un ressort suppl\u00e9mentaire qui lui permettait de travailler plus vite que les autres. Si un coll\u00e8gue emballe deux caisses, il s&rsquo;assure d&rsquo;en faire trois.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous \u00e9tions assis l\u00e0 et il disait : \u00ab\u00a0Je vais y arriver\u00a0\u00bb, se souvient Al Paturzo, qui travaillait aux c\u00f4t\u00e9s de Vultaggio \u00e0 l&rsquo;\u00e9poque et qui est aujourd&rsquo;hui son directeur des op\u00e9rations. \u00ab\u00a0Il ne disait pas cela parce qu&rsquo;il pensait qu&rsquo;il allait gagner au loto ou autre chose. C&rsquo;\u00e9tait gr\u00e2ce \u00e0 son travail acharn\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vultaggio quitta le magasin et cofonda une entreprise de distribution et de brassage d&rsquo;alcool. Il fit une petite fortune dans les liqueurs de malt, puis entra dans la cour des grands dans les ann\u00e9es 1990 lorsqu&rsquo;il s&rsquo;est tourn\u00e9 vers le th\u00e9. Ses bo\u00eetes de th\u00e9 glac\u00e9 AriZona \u00e9taient plus audacieuses (gr\u00e2ce \u00e0 leur emballage pastel), plus grandes (gr\u00e2ce \u00e0 l&rsquo;utilisation de bo\u00eetes de bi\u00e8re tallboy) et plus avantageuses (gr\u00e2ce \u00e0 leur prix de 99 cents) que le reste du march\u00e9. AriZona a rapidement d\u00e9pass\u00e9 Snapple et s&rsquo;est impos\u00e9 sur les \u00e9tag\u00e8res de tout le pays, aidant Vultaggio \u00e0 amasser une fortune estim\u00e9e aujourd&rsquo;hui \u00e0 6,2 milliards de dollars.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La cl\u00e9 de son succ\u00e8s n&rsquo;est pas seulement un travail acharn\u00e9, mais aussi un mode de pens\u00e9e non conventionnel. Il ne d\u00e9pense rien en marketing traditionnel, comme les spots t\u00e9l\u00e9vis\u00e9s et les panneaux d&rsquo;affichage, et compte plut\u00f4t sur le fait que ses boissons gagneront en popularit\u00e9 de mani\u00e8re organique si elles ont bon go\u00fbt, attirent l&rsquo;attention et sont vendues \u00e0 un bon prix. \u00ab\u00a0La meilleure publicit\u00e9 pour nous, ce sont les gens qui sont satisfaits de ce que nous proposons\u00a0\u00bb, explique-t-il. Il s&rsquo;en tient \u00e0 cette m\u00eame approche pour sa nouvelle gamme de th\u00e9s durs, bien qu&rsquo;<a href=\"https:\/\/www.forbes.com\/sites\/monicahunter-hart\/2023\/12\/06\/inside-arizona-iced-teas-bold-plan-to-challenge-twisted-tea\/?sh=3227d2177059\">il soit confront\u00e9 \u00e0 un g\u00e9ant de la cat\u00e9gorie qui fait de la publicit\u00e9 \u00e0 outrance<\/a>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il n&rsquo;est donc pas surprenant qu&rsquo;une grande partie des conseils commerciaux de M. Vultaggio soient \u00e9galement non traditionnels. Lors d&rsquo;entretiens r\u00e9cents \u00e0 son bureau et dans son usine flambant neuve de 300 millions de dollars \u00e0 Edison, dans le New Jersey, il a expliqu\u00e9 \u00e0 Forbes ce qu&rsquo;il pensait qu&rsquo;il fallait pour r\u00e9ussir et a donn\u00e9 ses conseils aux jeunes entrepreneurs.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">7 le\u00e7ons<\/span><\/h2>\n<h3><span style=\"font-weight: 400;\"> Quelle que soit la taille de votre entreprise, agissez comme si elle \u00e9tait petite.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u00ab\u00a0C&rsquo;est ainsi que l&rsquo;on r\u00e9ussit\u00a0\u00bb, affirme M. Vultaggio. Beaucoup de dirigeants de ces entreprises disent : \u00ab\u00a0Nous sommes grands, nous devons gaspiller de l&rsquo;argent, c&rsquo;est comme \u00e7a\u00a0\u00bb. Il explique que cette attitude l&rsquo;a aid\u00e9 \u00e0 maintenir le prix de ses c\u00e9l\u00e8bres canettes \u00e0 99 cents depuis la cr\u00e9ation de l&rsquo;entreprise en 1992. Pour ce faire, il doit constamment innover pour trouver de nouveaux moyens de r\u00e9duire les co\u00fbts, qu&rsquo;il s&rsquo;agisse d&rsquo;augmenter la vitesse de production, de livrer la nuit, d&rsquo;amincir les canettes ou de couvrir les contrats \u00e0 terme sur l&rsquo;aluminium. \u00ab\u00a0Vous pouvez gaspiller de l&rsquo;argent toute la journ\u00e9e, mais \u00e0 un moment ou \u00e0 un autre, vous devrez demander au consommateur de payer la facture.\u201d<\/span><\/p>\n<h3><span style=\"font-weight: 400;\"> Parlez \u00e0 tout le monde.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Ne discutez pas seulement de votre entreprise avec les cadres, mais aussi avec toutes les personnes impliqu\u00e9es de pr\u00e8s ou de loin dans l&rsquo;entreprise. Pendant la journ\u00e9e de travail d&rsquo;AriZona, il peut \u00eatre difficile de retrouver Vultaggio parce qu&rsquo;il se prom\u00e8ne constamment, discutant avec tout le monde, du r\u00e9ceptionniste \u00e0 l&rsquo;op\u00e9rateur de chariot \u00e9l\u00e9vateur. Les employ\u00e9s plaisantent en disant qu&rsquo;il ne pourrait jamais participer \u00e0 l&rsquo;\u00e9mission Undercover Boss (bien qu&rsquo;on le lui ait demand\u00e9 une fois) parce qu&rsquo;il conna\u00eet tout le monde. \u00ab\u00a0La plupart des gens pensent qu&rsquo;il y a du g\u00e9nie dans la r\u00e9solution des probl\u00e8mes\u00a0\u00bb, d\u00e9clare Ron Zeitoune, directeur de l&rsquo;usine. Mais il dit avoir appris de Vultaggio qu&rsquo;en r\u00e9alit\u00e9, \u00ab\u00a0le g\u00e9nie r\u00e9side dans la collecte de donn\u00e9es. Si vous n&rsquo;avez pas de bonnes donn\u00e9es, vous ne pouvez pas prendre une bonne d\u00e9cision. La plupart des gens s&rsquo;en remettent \u00e0 des personnes de haut niveau pour leur donner une image du probl\u00e8me \u00e0 des milliers de kilom\u00e8tres de distance. Don ne commet pas cette erreur. S&rsquo;il veut voir comment quelque chose fonctionne, il appelle litt\u00e9ralement la personne qui travaille sur cette chose\u00a0\u00bb.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\"> Faites comme si votre famille travaillait pour votre entreprise.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Vultaggio se souvient d&rsquo;avoir visit\u00e9 son ancienne usine il y a plusieurs ann\u00e9es et d&rsquo;avoir trouv\u00e9 les toilettes sales et d\u00e9pourvues de savon et d&rsquo;essuie-tout. Il se souvient d&rsquo;avoir dit au directeur : \u00ab\u00a0Ce n&rsquo;est pas comme \u00e7a que je fonctionne\u00a0\u00bb. \u00ab\u00a0Car si votre s\u0153ur, votre m\u00e8re ou votre tante travaillait l\u00e0, je pense que cela les d\u00e9couragerait. Vous devez faire les choses comme si votre famille travaillait l\u00e0\u00a0\u00bb. (Vultaggio a gard\u00e9 cette philosophie \u00e0 l&rsquo;esprit lors de la conception de sa nouvelle usine, en privil\u00e9giant le confort et la commodit\u00e9 des employ\u00e9s gr\u00e2ce \u00e0 des am\u00e9nagements tels qu&rsquo;une salle de sport dot\u00e9e d&rsquo;un mur en verre qui surplombe les machines.)<\/span><\/p>\n<h3><span style=\"font-weight: 400;\"> Votre lieu de travail peut et doit \u00eatre beau.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u00ab\u00a0La plupart des gens ne peignent pas leurs colonnes en rose et en vert et n&rsquo;y mettent pas des pois\u00a0\u00bb, dit Vultaggio. Lui, il le fait. Il est convaincu que l&rsquo;esth\u00e9tique d&rsquo;un lieu de travail a un impact \u00e9norme sur le moral des employ\u00e9s. Il a donc pris en compte les suggestions des travailleurs de l&rsquo;usine pour le nouveau d\u00e9cor, qui rappelle par endroits celui de Disneyland et comprend de faux cerisiers en fleurs, des expositions de voitures anciennes et des portes peintes de fresques repr\u00e9sentant le soleil se couchant sur des cactus saguaro. Chaque peinture murale a co\u00fbt\u00e9 400 dollars. \u00ab\u00a0C&rsquo;est de l&rsquo;argent bien d\u00e9pens\u00e9. Cela rend l&rsquo;endroit plus accueillant\u00a0\u00bb, d\u00e9clare M. Vultaggio. Les usines ressemblent g\u00e9n\u00e9ralement \u00e0 des donjons ou \u00e0 des prisons russes. Mais dans son cas ? \u00ab\u00a0On dirait une galerie d&rsquo;art. Pourquoi ne le serait-elle pas ?\u201d<\/span><\/p>\n<h3><span style=\"font-weight: 400;\"> Accepter l&rsquo;\u00e9ducation non traditionnelle en dehors de la salle de classe.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Vultaggio a failli abandonner le lyc\u00e9e. Distrait et probablement dyslexique, il a eu des notes catastrophiques &#8211; il n&rsquo;a r\u00e9ussi l&rsquo;espagnol qu&rsquo;en convainquant le professeur qu&rsquo;il \u00e9tait un trop bon \u00e9l\u00e8ve pour \u00e9chouer (il dit que c&rsquo;est \u00e0 ce moment-l\u00e0 qu&rsquo;il a appris l&rsquo;importance d&rsquo;\u00eatre un vendeur). Il n&rsquo;a jamais lu un livre. Mais il apprend tout au long de sa vie. Il a acquis des comp\u00e9tences en math\u00e9matiques en travaillant dans une \u00e9picerie et a appris \u00e0 parler espagnol dans les rues de New York. \u00ab\u00a0Je ne dis pas que l&rsquo;\u00e9cole est une mauvaise chose\u00a0\u00bb, d\u00e9clare-t-il, soulignant qu&rsquo;elle fonctionne pour beaucoup de gens. Mais pour lui ? \u00ab\u00a0Ce n&rsquo;\u00e9tait qu&rsquo;une perte de temps. Ce que j&rsquo;ai appris en dehors de l&rsquo;\u00e9cole \u00e9tait bien plus important que ce que j&rsquo;ai appris \u00e0 l&rsquo;\u00e9cole.\u201d<\/span><\/p>\n<h3><span style=\"font-weight: 400;\"> Ne demandez pas \u00e0 vos employ\u00e9s de faire quelque chose que vous ne feriez pas.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Bien s\u00fbr, une journ\u00e9e typique de Vultaggio comprend les d\u00e9cisions de haut niveau pr\u00e9visibles et les tests d&rsquo;ar\u00f4mes. Mais vous le trouverez aussi en train de balayer, de passer la serpilli\u00e8re et de d\u00e9placer des meubles. \u00ab\u00a0Il ne nous dit pas de faire quelque chose qu&rsquo;il ne ferait pas\u00a0\u00bb, d\u00e9clare Amish Patel, responsable des op\u00e9rations. Cela permet aux employ\u00e9s de se sentir respect\u00e9s et donne \u00e0 M. Vultaggio l&rsquo;occasion de montrer comment il veut qu&rsquo;une t\u00e2che soit accomplie. Lors d&rsquo;une journ\u00e9e m\u00e9morable, il y a quelques mois, il a conduit un chariot \u00e9l\u00e9vateur pendant huit heures d&rsquo;affil\u00e9e pour montrer \u00e0 l&rsquo;\u00e9quipe comment organiser leur nouvel entrep\u00f4t. \u00ab\u00a0Il ne s\u2019arr\u00eatera pas de conduire jusqu&rsquo;\u00e0 ce qu&rsquo;il soit fatigu\u00e9. Il va faire le travail\u00a0\u00bb, explique Zeitoune, directeur de l&rsquo;usine. \u00ab\u00a0Il va le faire lui-m\u00eame et nous montrer. Et nous avons appris ce jour-l\u00e0.\u201d<\/span><\/p>\n<h3><span style=\"font-weight: 400;\"> Marchez avec un caillou dans votre chaussure.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u00ab\u00a0Dans les affaires, il faut marcher avec un caillou dans la chaussure. Chaque fois que vous faites un pas, vous sentez ce caillou\u00a0\u00bb, explique M. Vultaggio. \u00ab\u00a0Cela vous rappelle qu&rsquo;il ne faut rien prendre pour acquis. Si vous vous sentez trop \u00e0 l&rsquo;aise, vous tombez dans des habitudes paresseuses. Dans le commerce de d\u00e9tail, cela peut signifier ne pas suivre de pr\u00e8s l&rsquo;\u00e9volution des go\u00fbts des consommateurs. Selon M. Vultaggio, c&rsquo;est ce qui s&rsquo;est pass\u00e9 avec A&amp;P et Sears, des conglom\u00e9rats autrefois gigantesques qui ont fait faillite et sont tomb\u00e9s dans l&rsquo;oubli : Ils ont agi comme si \u00ab\u00a0les clients n&rsquo;avaient pas d&rsquo;importance\u00a0\u00bb et ont mis les mauvais articles en rayon. \u00ab\u00a0C&rsquo;est ce genre d&rsquo;attitude qui vous conduit \u00e0 la faillite\u00a0\u00bb, pr\u00e9vient-il. \u00ab\u00a0La concurrence finira toujours par s&rsquo;imposer.\u201d<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Don Vultaggio, patron d&rsquo;Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu&rsquo;il n&rsquo;avait qu&rsquo;un dipl\u00f4me de fin d&rsquo;\u00e9tudes secondaires. Voici sept conseils tir\u00e9s de son ascension entrepreneuriale. Au milieu des ann\u00e9es 1960, des d\u00e9cennies avant de cr\u00e9er l&rsquo;entreprise qui allait exploser pour devenir l&#8217;empire du th\u00e9 glac\u00e9 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[19,16],"tags":[],"class_list":["post-966","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entrepreneurs","category-finance"],"acf":[],"_yoast_wpseo_title":null,"_yoast_wpseo_metadesc":"Don Vultaggio, patron d'Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu'il n'avait qu'un dipl\u00f4me d'\u00e9tudes secondaires.","auteur_traducteur":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 le\u00e7ons d&#039;affaires non conventionnelles d&#039;un milliardaire du th\u00e9 glac\u00e9 | Forbes Belgique<\/title>\n<meta name=\"description\" content=\"Don Vultaggio, patron d&#039;Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu&#039;il n&#039;avait qu&#039;un dipl\u00f4me d&#039;\u00e9tudes secondaires.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 le\u00e7ons d&#039;affaires non conventionnelles d&#039;un milliardaire du th\u00e9 glac\u00e9 | Forbes Belgique\" \/>\n<meta property=\"og:description\" content=\"Don Vultaggio, patron d&#039;Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu&#039;il n&#039;avait qu&#039;un dipl\u00f4me d&#039;\u00e9tudes secondaires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/\" \/>\n<meta property=\"og:site_name\" content=\"Forbes Belgique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/forbesbelgique\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T05:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-17T08:25:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/Arizona-Beverages-e1721204698913.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2017\" \/>\n\t<meta property=\"og:image:height\" content=\"1055\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Forbes Belgique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Forbes Belgique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/\"},\"author\":{\"name\":\"Forbes Belgique\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/147c95cac22c7a4a8056e69e1f287b1f\"},\"headline\":\"7 le\u00e7ons d&rsquo;affaires non conventionnelles d&rsquo;un milliardaire du th\u00e9 glac\u00e9\",\"datePublished\":\"2024-07-12T05:00:34+00:00\",\"dateModified\":\"2024-07-17T08:25:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/\"},\"wordCount\":1574,\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Arizona-Beverages-e1721204698913.webp\",\"articleSection\":[\"Entrepreneurs\",\"Finance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/\",\"name\":\"7 le\u00e7ons d'affaires non conventionnelles d'un milliardaire du th\u00e9 glac\u00e9 | Forbes Belgique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Arizona-Beverages-e1721204698913.webp\",\"datePublished\":\"2024-07-12T05:00:34+00:00\",\"dateModified\":\"2024-07-17T08:25:13+00:00\",\"description\":\"Don Vultaggio, patron d'Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu'il n'avait qu'un dipl\u00f4me d'\u00e9tudes secondaires.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Arizona-Beverages-e1721204698913.webp\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Arizona-Beverages-e1721204698913.webp\",\"width\":2017,\"height\":1055},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 le\u00e7ons d&rsquo;affaires non conventionnelles d&rsquo;un milliardaire du th\u00e9 glac\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"name\":\"Forbes Belgique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#organization\",\"name\":\"Forbes Belgique\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/forbes.be_.png\",\"width\":1200,\"height\":675,\"caption\":\"Forbes Belgique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/forbesbelgique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/Forbes_Belgium\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/forbes-belgium\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/#\\\/schema\\\/person\\\/147c95cac22c7a4a8056e69e1f287b1f\",\"name\":\"Forbes Belgique\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/forbes-thumb-150x150.jpg\",\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/forbes-thumb-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/forbes-thumb-150x150.jpg\",\"caption\":\"Forbes Belgique\"},\"url\":\"https:\\\/\\\/www.forbes.be\\\/fr\\\/author\\\/forbes-be\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 le\u00e7ons d'affaires non conventionnelles d'un milliardaire du th\u00e9 glac\u00e9 | Forbes Belgique","description":"Don Vultaggio, patron d'Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu'il n'avait qu'un dipl\u00f4me d'\u00e9tudes secondaires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/","og_locale":"fr_FR","og_type":"article","og_title":"7 le\u00e7ons d'affaires non conventionnelles d'un milliardaire du th\u00e9 glac\u00e9 | Forbes Belgique","og_description":"Don Vultaggio, patron d'Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu'il n'avait qu'un dipl\u00f4me d'\u00e9tudes secondaires.","og_url":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/","og_site_name":"Forbes Belgique","article_publisher":"https:\/\/www.facebook.com\/forbesbelgique\/","article_published_time":"2024-07-12T05:00:34+00:00","article_modified_time":"2024-07-17T08:25:13+00:00","og_image":[{"width":2017,"height":1055,"url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/Arizona-Beverages-e1721204698913.webp","type":"image\/webp"}],"author":"Forbes Belgique","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Forbes Belgique","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/#article","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/"},"author":{"name":"Forbes Belgique","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/147c95cac22c7a4a8056e69e1f287b1f"},"headline":"7 le\u00e7ons d&rsquo;affaires non conventionnelles d&rsquo;un milliardaire du th\u00e9 glac\u00e9","datePublished":"2024-07-12T05:00:34+00:00","dateModified":"2024-07-17T08:25:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/"},"wordCount":1574,"publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/Arizona-Beverages-e1721204698913.webp","articleSection":["Entrepreneurs","Finance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/","url":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/","name":"7 le\u00e7ons d'affaires non conventionnelles d'un milliardaire du th\u00e9 glac\u00e9 | Forbes Belgique","isPartOf":{"@id":"https:\/\/www.forbes.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/#primaryimage"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/Arizona-Beverages-e1721204698913.webp","datePublished":"2024-07-12T05:00:34+00:00","dateModified":"2024-07-17T08:25:13+00:00","description":"Don Vultaggio, patron d'Arizona Beverages, est pass\u00e9 des rues de Brooklyn \u00e0 la liste des milliardaires de Forbes alors qu'il n'avait qu'un dipl\u00f4me d'\u00e9tudes secondaires.","breadcrumb":{"@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/#primaryimage","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/Arizona-Beverages-e1721204698913.webp","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/Arizona-Beverages-e1721204698913.webp","width":2017,"height":1055},{"@type":"BreadcrumbList","@id":"https:\/\/www.forbes.be\/fr\/7-lecons-daffaires-non-conventionnelles-dun-milliardaire-du-the-glace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.forbes.be\/fr\/"},{"@type":"ListItem","position":2,"name":"7 le\u00e7ons d&rsquo;affaires non conventionnelles d&rsquo;un milliardaire du th\u00e9 glac\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.forbes.be\/fr\/#website","url":"https:\/\/www.forbes.be\/fr\/","name":"Forbes Belgique","description":"","publisher":{"@id":"https:\/\/www.forbes.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.forbes.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.forbes.be\/fr\/#organization","name":"Forbes Belgique","url":"https:\/\/www.forbes.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/02\/forbes.be_.png","width":1200,"height":675,"caption":"Forbes Belgique"},"image":{"@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/forbesbelgique\/","https:\/\/www.instagram.com\/Forbes_Belgium","https:\/\/www.linkedin.com\/company\/forbes-belgium\/"]},{"@type":"Person","@id":"https:\/\/www.forbes.be\/fr\/#\/schema\/person\/147c95cac22c7a4a8056e69e1f287b1f","name":"Forbes Belgique","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/forbes-thumb-150x150.jpg","url":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/forbes-thumb-150x150.jpg","contentUrl":"https:\/\/www.forbes.be\/fr\/wp-content\/uploads\/2024\/01\/forbes-thumb-150x150.jpg","caption":"Forbes Belgique"},"url":"https:\/\/www.forbes.be\/fr\/author\/forbes-be\/"}]}},"_links":{"self":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/comments?post=966"}],"version-history":[{"count":4,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/966\/revisions"}],"predecessor-version":[{"id":1064,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/posts\/966\/revisions\/1064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media\/981"}],"wp:attachment":[{"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/media?parent=966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/categories?post=966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.forbes.be\/fr\/wp-json\/wp\/v2\/tags?post=966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}